{"id":11146,"date":"2016-09-20T15:33:45","date_gmt":"2016-09-20T15:33:45","guid":{"rendered":"https:\/\/healthbrain.wpengine.com\/fr\/?p=11146"},"modified":"2019-10-18T12:48:31","modified_gmt":"2019-10-18T12:48:31","slug":"trouble-panique-agoraphobie","status":"publish","type":"post","link":"https:\/\/yourbrain.health\/fr\/trouble-panique-agoraphobie\/","title":{"rendered":"Troubles de paniques avec agoraphobie, d\u00e9couvrez l&#8217;histoire de Maria"},"content":{"rendered":"\n<p style=\"text-align:center\"><strong>Qu&#8217;est-ce que l&#8217;agoraphobie ? Comment commence-t-elle ? Qu&#8217;est-ce que cela implique ? Existe-t-il un traitement ?<\/strong>&nbsp;Les troubles de paniques avec agoraphobie sont parmi les&nbsp;plus courants en consultation et \u00e9galement l&#8217;un des plus incapacitants. Cette maladie g\u00e9n\u00e8re chez les personnes qui en souffrent une d\u00e9t\u00e9rioration importante du fonctionnement social et professionnel, ce qui affecte grandement leur qualit\u00e9 de vie. Dans cet article nous vous racontons l&#8217;histoire de Maria, une femme sujette au trouble de panique avec agoraphobie.<\/p>\n\n\n\n<div class=\"wp-block-image Agoraphobie wp-image-6553 size-full\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/healthbrain.wpengine.com\/wp-content\/uploads\/2016\/09\/agorafobia-640x360.jpg\" alt=\"Qu'est-ce que l'agoraphobie et comment commence-t-elle ?\" class=\"wp-image-58388\" srcset=\"https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/agorafobia-640x360.jpg 640w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/agorafobia-300x169.jpg 300w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/agorafobia-768x432.jpg 768w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/agorafobia.jpg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption> Qu&#8217;est-ce que l&#8217;agoraphobie et comment commence-t-elle ? <\/figcaption><\/figure><\/div>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04e1d9385bc\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04e1d9385bc\" checked aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/yourbrain.health\/fr\/trouble-panique-agoraphobie\/#Maria_victime_de_troubles_de_paniques_et_dagoraphobie_Decouvrez_les_phases_de_cette_maladie\" >Maria, victime de troubles de paniques et d&#8217;agoraphobie. D\u00e9couvrez les phases de cette maladie<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/yourbrain.health\/fr\/trouble-panique-agoraphobie\/#Comment_commence_lagoraphobie_La_premiere_attaque_de_panique\" >Comment commence l&#8217;agoraphobie ? La premi\u00e8re attaque de panique<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/yourbrain.health\/fr\/trouble-panique-agoraphobie\/#Lagoraphobie_commence_quand_vous_commencez_a_eviter_les_lieux_dans_lesquels_vous_pensez_que_vous_pouvez_souffrir_dune_attaque_de_panique\" >L&#8217;agoraphobie commence quand vous commencez \u00e0 \u00e9viter les lieux dans lesquels vous pensez que vous pouvez souffrir d&#8217;une attaque de panique<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/yourbrain.health\/fr\/trouble-panique-agoraphobie\/#Quest-ce_qui_maintient_lagoraphobie\" >Qu&#8217;est-ce qui maintient l&#8217;agoraphobie ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/yourbrain.health\/fr\/trouble-panique-agoraphobie\/#Repercussions_sociales_et_professionnelles_de_lagoraphobie\" >R\u00e9percussions sociales et&nbsp;professionnelles&nbsp;de l&#8217;agoraphobie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/yourbrain.health\/fr\/trouble-panique-agoraphobie\/#Existe-t-il_un_traitement_pour_lagoraphobie\" >Existe-t-il un traitement pour l&#8217;agoraphobie ?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Maria_victime_de_troubles_de_paniques_et_dagoraphobie_Decouvrez_les_phases_de_cette_maladie\"><\/span><strong>Maria, victime de troubles de paniques et d&#8217;agoraphobie. D\u00e9couvrez les phases de cette maladie<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comment_commence_lagoraphobie_La_premiere_attaque_de_panique\"><\/span><strong>Comment commence l&#8217;agoraphobie ? La premi\u00e8re attaque de panique<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><em>Maria nous raconte comment tout a commenc\u00e9&#8230;<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>&#8220;Cela fait 4 ans, alors que j&#8217;allais en voiture au travail. J&#8217;\u00e9tais parfaitement bien, mais soudainement j&#8217;ai commenc\u00e9 \u00e0 me sentir mal, comme si j&#8217;\u00e9touffais, j&#8217;avais des palpitations, des naus\u00e9es. Je ne savais ce qu&#8217;il me passait. Jamais auparavant je n&#8217;avais ressenti une telle sensation. Je&nbsp;pensais&nbsp;que je faisais un infarctus et que j&#8217;allais mourir&#8230;&#8221;<\/em><\/p><p><em>&#8220;Quand j&#8217;ai pu retrouver mon souffle je suis all\u00e9e tout de suite aux urgences, o\u00f9 ils m&#8217;ont assur\u00e9 que je n&#8217;avais rien et que mon&nbsp;c\u0153ur&nbsp;\u00e9tait en parfait \u00e9tat. Cette information me&nbsp;tranquillisa&nbsp;dans un premier temps, mais j&#8217;ai ensuite commenc\u00e9 \u00e0 ruminer&#8230; et je ne pouvais pas croire que ce qui m&#8217;\u00e9tais arriv\u00e9 n&#8217;\u00e9tais rien, je continuais donc de penser que je&nbsp;souffrais&nbsp;gravement du&nbsp;c\u0153ur.<\/em><em>&#8220;<\/em><\/p><\/blockquote>\n\n\n\n<p>Ce jour, Maria a en fait souffert d&#8217;une attaque de panique. Souvent, le d\u00e9clenchement de ces attaques est d\u00fb \u00e0 des \u00e9v\u00e9nements stressant dans la vie de la personne qui la subit. Dans ce cas pr\u00e9cis, Maria avait des probl\u00e8mes au travail, car elle ne s&#8217;entendait pas bien avec ses coll\u00e8gues et avait eu r\u00e9cemment une forte dispute avec son partenaire de couple.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201c\u2026Apr\u00e8s&nbsp;cette premi\u00e8re attaque, chaque fois que je notais la moindre sensation dans mon corps (battement du&nbsp;c\u0153ur, respiration, etc&#8230;) je pensais que j&#8217;allais \u00e0 nouveau avoir une attaque et que j&#8217;allais mourir. Cette id\u00e9e me g\u00e9n\u00e9rait beaucoup d&#8217;anxi\u00e9t\u00e9 et de mal-\u00eatre. Quand cela arrivait, je terminais toujours aux urgences, car cela \u00e9tait la seule mani\u00e8re de soulager mon anxi\u00e9t\u00e9&#8230;&#8221; &#8220;C&#8217;est horrible de sentir que tu vas avoir une attaque cardiaque et que tu peux en mourir \u00e0 n&#8217;importe quel moment. Cette pens\u00e9e \u00e9tait pr\u00e9sente&nbsp;constamment&nbsp;dans ma t\u00eate, je n&#8217;arrivais pas \u00e0 m&#8217;en d\u00e9faire, m\u00eame si j&#8217;essayais de toutes mes forces&#8221;&#8230;<\/em><\/p><\/blockquote>\n\n\n\n<p>\u00c0 partir de cette premi\u00e8re attaque de panique, chaque fois que Maria percevait un petit changement dans son corps elle r\u00e9pondait avec de l&#8217;anxi\u00e9t\u00e9, par anticipation \u00e0 une nouvelle attaque.<\/p>\n\n\n\n<p>Des r\u00e9actions qui \u00e9taient auparavant inoffensives pour Maria \u00e9taient d\u00e9sormais la cause d&#8217;une grande peur : <strong>des&nbsp;<\/strong><strong>changements qui survenait naturellement dans son organisme<\/strong>&nbsp;comme l&#8217;ovulation, le processus digestif,&nbsp;<strong>ou des changements dus \u00e0 ses activit\u00e9s externes,&nbsp;<\/strong>comme de l&#8217;exercice, la relaxation, etc&#8230;<\/p>\n\n\n\n<p>La r\u00e9ponse par la peur \u00e0 ses petits changements dans son organisme g\u00e9n\u00e9rait alors une plus grande r\u00e9action dans son corps, ce \u00e0 quoi elle r\u00e9agissait avec une peur encore plus grande. La prochaine <a href=\"https:\/\/healthbrain.wpengine.com\/fr\/attaques-de-panique-crises-dangoisse\/\" target=\"_blank\" rel=\"noopener noreferrer\">attaque de panique<\/a> ne tardait alors pas \u00e0 survenir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Lagoraphobie_commence_quand_vous_commencez_a_eviter_les_lieux_dans_lesquels_vous_pensez_que_vous_pouvez_souffrir_dune_attaque_de_panique\"><\/span><strong>L&#8217;agoraphobie commence quand vous commencez \u00e0 \u00e9viter les lieux dans lesquels vous pensez que vous pouvez souffrir d&#8217;une attaque de panique<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cPar la suite, chaque fois que je devais prendre la voiture, je devenais tr\u00e8s anxieuse car je pensais que j&#8217;allais souffrir d&#8217;une autre attaque de panique. Ainsi que je fini par me d\u00e9cider \u00e0 ne plus conduire, ce qui me g\u00e9n\u00e9ra un grand soulagement dans un premier temps&#8221;<\/em><\/p><p><em>&#8220;&#8230;ensuite, j&#8217;ai commenc\u00e9 \u00e0 \u00e9viter le&nbsp;m\u00e9tro, puis le bus, le train, car je pensais que l\u00e0 aussi je pourrais souffrir d&#8217;une attaque de panique. Et cela furent les premiers d&#8217;une liste interminable de lieux dans lesquels je ne pouvais pas me rendre&#8230; je n&#8217;allais plus au cin\u00e9ma, ni aux concerts, j&#8217;ai arr\u00eat\u00e9 de sortir avec mes amies et en couple, pour r\u00e9sumer, j&#8217;ai arr\u00eat\u00e9 d&#8217;avoir une vie<\/em><\/p><p><em>\u201d.<\/em><\/p><\/blockquote>\n\n\n\n<p><strong>Maria apprit \u00e0 associer l&#8217;attaque de panique avec le lieu dans lequel c&#8217;\u00e9tait produite cette dite attaque, dans ce cas sa voiture, et a commenc\u00e9 \u00e0 \u00e9viter de la prendre<\/strong>&nbsp;et c&#8217;est \u00e0 ce moment qu&#8217;ont commenc\u00e9 les conduites agora-phobiques.<\/p>\n\n\n\n<p>Ensuite, Maria commen\u00e7a \u00e0 \u00e9viter d&#8217;autres lieux. Des lieux dans lesquels elle n&#8217;avait jamais eu d&#8217;attaque de panique, mais dans lesquels elle pensait que celles-ci pourraient se produire, ce qui lui \u00e9tait suffisant pour avoir envie de les \u00e9viter.<\/p>\n\n\n\n<p>Des t\u00e9moignages de patients comme Maria affirment que le motif pour lequel ils refusent de se rendre dans certains lieux est en lien avec la peur de subir une attaque, et que personne ne puisse les aider ou que cela soit compliquer de s&#8217;enfuir en urgence afin de se mettre \u00e0 l&#8217;abri.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quest-ce_qui_maintient_lagoraphobie\"><\/span><strong>Qu&#8217;est-ce qui maintient l&#8217;agoraphobie ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201c\u2026quand mes amis me proposaient d&#8217;aller au cin\u00e9ma, je devenais tr\u00e8s anxieuse car je pensais que je pourrais avoir l\u00e0-bas une attaque de panique et que personne ne pourrait m&#8217;aider&#8230; que je ne pourrais pas m&#8217;enfuir d&#8217;un tel endroit&#8230; et cela&nbsp;m\u2019apeurait&nbsp;beaucoup&#8221;.<\/em><\/p><p><em>&#8220;&#8230;Afin d&#8217;en finir avec ces sensations si d\u00e9sagr\u00e9ables d&#8217;anxi\u00e9t\u00e9, je finissais par refuser toutes les invitations \u00e0 sortir de mes amis et alors je me sentais vraiment soulag\u00e9e, car l&#8217;anxi\u00e9t\u00e9&nbsp;disparaissait&#8230;&#8221;<\/em><\/p><\/blockquote>\n\n\n\n<p><strong>Chaque fois que Maria anticipait la possibilit\u00e9 de se rendre dans un de &#8220;ces lieux&#8221; elle&nbsp;commen\u00e7ait&nbsp;\u00e0 d\u00e9velopper des sympt\u00f4mes d&#8217;anxi\u00e9t\u00e9,<\/strong>&nbsp;et finissait donc par les \u00e9viter avec comme objectif d&#8217;en finir avec cette anxi\u00e9t\u00e9. Maria apprit \u00e0 associer l&#8217;\u00e9vitement avec le soulagement de mettre un terme \u00e0 cette anxi\u00e9t\u00e9 que lui g\u00e9n\u00e9rait l&#8217;id\u00e9e de se rendre dans ces lieux.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Repercussions_sociales_et_professionnelles_de_lagoraphobie\"><\/span><strong>R\u00e9percussions sociales et&nbsp;professionnelles&nbsp;de l&#8217;agoraphobie<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201c\u2026j&#8217;ai perdu mes amis, j&#8217;ai perdu mon partenaire de couple, j&#8217;ai perdu mon travail&#8230; j&#8217;ai tout perdu, tout ce que j&#8217;avais&#8230; Je me sentais incapable de tout et mon estime de moi-m\u00eame \u00e9tait au plancher. La plus grande partie du temps j&#8217;\u00e9tais triste, car je n&#8217;arrivais plus \u00e0 profiter de ce qui avant me rendait heureuse, je n&#8217;arrivais plus \u00e0 bien dormir, et j&#8217;en suis arriver \u00e0 penser \u00e0 mettre fin \u00e0 mes jours&#8230;&#8221;<\/em><\/p><p><em>&#8220;Le trouble \u00e0 finit par se convertir en ma vie, et je n&#8217;avais plus d&#8217;espace pour rien d&#8217;autre. Le pire fut de voir comment les gens qui tenaient \u00e0 moi s&#8217;\u00e9loignaient petit \u00e0 petit car ils sentaient qu&#8217;ils ne pouvaient rien faire pour m&#8217;aider. J&#8217;en suis arriv\u00e9 \u00e0 un moment \u00e0 me retrouver seule, seule avec mon trouble, et tout le reste cessa de m&#8217;importer<\/em><em>\u201d &nbsp;<\/em><\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Existe-t-il_un_traitement_pour_lagoraphobie\"><\/span><strong>Existe-t-il un traitement pour l&#8217;agoraphobie ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cIl y a 4 ans je vous aurais dit que non, qu&#8217;il n&#8217;existait aucune solution. Sans m&#8217;en rendre compte, je m&#8217;\u00e9tais mise dans un trou que j&#8217;avais creus\u00e9 moi-m\u00eame et duquel je ne savais pas comment sortir.&#8221;<\/em><\/p><p><em>&#8220;&#8230;Je ne peux pas cesser d&#8217;\u00eatre \u00e9mue en pensant \u00e0 l&#8217;aide inconditionnelle que m&#8217;a donn\u00e9 ma famille et qu&#8217;elle continue de me donner. Sans son soutien, sortir de ce trou m&#8217;aurais \u00e9t\u00e9 impossible. Ce sont eux qui m&#8217;ont encourag\u00e9 d&#8217;aller voir un m\u00e9decin et une fois sur place j&#8217;ai eu la chance d&#8217;avoir affaire \u00e0 de tr\u00e8s bons professionnels. Le chemin fut loin d&#8217;\u00eatre facile, mais aujourd&#8217;hui je peux dire que m\u00eame si je ne suis pas totalement remise, ma vie est redevenue relativement normale. Il y a toujours certains lieux o\u00f9 je ne peux pas me rendre, mais quelque chose me dit que cela va changer&nbsp;et que je finirais par vaincre mes peurs<\/em><em>\u2026\u201d<\/em><\/p><\/blockquote>\n\n\n\n<p>Maria fut trait\u00e9e dans un centre m\u00e9dical o\u00f9 <a href=\"https:\/\/healthbrain.wpengine.com\/fr\/psychiatre-ou-psychologue\/\" target=\"_blank\" rel=\"noopener noreferrer\">psychologue et psychiatre<\/a> ont collabor\u00e9s conjointement pour l&#8217;aider.<\/p>\n\n\n\n<p>Maria a re\u00e7u un traitement combin\u00e9, compos\u00e9 de m\u00e9dicaments pharmacologiques antid\u00e9presseurs et anxiolytiques, joint \u00e0 une th\u00e9rapie cognitive comportementale, suivant ainsi les recommandations avec fermet\u00e9 et constance afin de traiter le trouble duquel elle souffrait.<\/p>\n\n\n\n<p>Aujourd&#8217;hui Maria continue de se rendre au centre de sant\u00e9 mentale et bien qu&#8217;elle ait r\u00e9alis\u00e9e beaucoup de progr\u00e8s, il lui reste encore un peu de chemin \u00e0 parcourir avant de vaincre totalement ce trouble.<\/p>\n\n\n\n<p><span style=\"font-size: 11.5pt; font-family: 'Verdana',sans-serif; color: #111111;\">Merci beaucoup de nous avoir lu, nous esp\u00e9rons que cet article vous aura plus et surtout que le t\u00e9moignage de Maria vous aura \u00e9t\u00e9 utile \u00e0 comprendre ce qu&#8217;est l&#8217;agoraphobie. N&#8217;h\u00e9sitez pas \u00e0 laisser vos commentaires et vos questions sur le sujet plus bas, nous serons enchant\u00e9s d&#8217;y r\u00e9pondre. \ud83d\ude42<\/span><\/p>\n\n\n\n<p>&#8220;Source&nbsp;: Beatriz Marques, psychologue de Cognifit experte de l\u2019anxi\u00e9t\u00e9 et du stress.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&#8217;est-ce que l&#8217;agoraphobie ? Comment commence-t-elle ? Qu&#8217;est-ce que cela implique ? Existe-t-il un traitement ?&nbsp;Les troubles de paniques avec agoraphobie sont parmi les&nbsp;plus courants [&#8230;]<\/p>\n","protected":false},"author":28,"featured_media":58388,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3490],"tags":[4601,3496,4604,4602,4603],"class_list":["post-11146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante","tag-agoraphobie","tag-anxiete","tag-attaque-de-panique","tag-traitement-de-lagoraphobie","tag-trouble-de-panique"],"_links":{"self":[{"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/posts\/11146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/comments?post=11146"}],"version-history":[{"count":0,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/posts\/11146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/media\/58388"}],"wp:attachment":[{"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/media?parent=11146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/categories?post=11146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/tags?post=11146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}