{"id":10634,"date":"2016-09-16T15:42:12","date_gmt":"2016-09-16T15:42:12","guid":{"rendered":"https:\/\/healthbrain.wpengine.com\/fr\/?p=10634"},"modified":"2019-10-23T16:01:26","modified_gmt":"2019-10-23T16:01:26","slug":"psychologie-positive","status":"publish","type":"post","link":"https:\/\/yourbrain.health\/fr\/psychologie-positive\/","title":{"rendered":"7 trucs de psychologie positive : comment \u00eatre plus optimiste et plus heureux ?"},"content":{"rendered":"\n<p><em>Quelle id\u00e9e vous faites-vous du bonheur ? Qu&#8217;est-ce qui selon vous vous rend heureux ? Il est possible que beaucoup d&#8217;entre vous ont pens\u00e9s \u00e0 l&#8217;argent. Pourtant les \u00e9tudes affirment que l&#8217;influence de l&#8217;argent sur le bonheur des gens est finalement assez faible. D\u00e9couvrez dans cet article <strong>7 trucs de psychologie positive, afin que vous soyez plus optimiste et plus heureux :<\/strong><\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p style=\"text-align: left;\">Les experts soutiennent que <strong>le bonheur d\u00e9pend de trois facteurs :&nbsp;<\/strong>environ 50% d\u00e9pend de notre caract\u00e8re qui est d\u00e9termin\u00e9&nbsp;<strong>g\u00e9n\u00e9tiquement,&nbsp;<\/strong>environ 10% d\u00e9pend des <strong>succ\u00e8s accomplis&nbsp;<\/strong>au cours de notre vie et environ 40% d\u00e9pend de <strong>c<\/strong><strong>e que nous faisons nous-m\u00eame pour \u00eatre heureux.<\/strong><\/p><\/blockquote>\n\n\n\n<p>Cela signifie que nous avons beaucoup de marge de man\u0153uvre par rapport \u00e0 notre propre bien\u00eatre. Comment faire pour augmenter ce dernier ? Continuez votre lecture pour connaitre les cl\u00e9s du bonheur :<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04e1e01b52e\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04e1e01b52e\" checked aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#Quest-ce_que_la_psychologie_positive\" >Qu&#8217;est-ce que la psychologie positive ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#Filtrage_Selectif_pourquoi_tendons-nous_a_nous_souvenir_des_choses_negatives\" >Filtrage&nbsp;S\u00e9lectif&nbsp;: pourquoi tendons-nous \u00e0 nous souvenir des choses n\u00e9gatives ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#Trucs_de_psychologie_positive_exercices_et_techniques_pour_augmenter_les_emotions_positives\" >Trucs de psychologie positive : exercices et techniques pour augmenter les \u00e9motions positives<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#1_Truc_de_psychologie_positive_petits_plaisirs\" >1. Truc de psychologie positive : petits plaisirs<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#2_Truc_de_psychologie_positive_vos_forces\" >2.&nbsp;Truc de psychologie positive : vos forces<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#3_Truc_de_psychologie_positive_appui_social\" >3.&nbsp;Truc de psychologie positive : appui social<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#4Truc_de_psychologie_positive_exercice\" >4.Truc de psychologie positive : exercice<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#5_Truc_de_psychologie_positive_relations_sexuelles\" >5.&nbsp;Truc de psychologie positive : relations sexuelles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#6_Truc_de_psychologie_positive_intensifier_le_niveau_dactivite\" >6.&nbsp;Truc de psychologie positive :&nbsp;intensifier le niveau d&#8217;activit\u00e9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/yourbrain.health\/fr\/psychologie-positive\/#7_Truc_de_psychologie_positive_reconnaissance\" >7.&nbsp;Truc de psychologie positive : reconnaissance<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quest-ce_que_la_psychologie_positive\"><\/span><strong>Qu&#8217;est-ce que la psychologie positive ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La Psychologie Positive est une nouvelle branche de la Psychologie qui \u00e9tudie les \u00e9motions positives et leurs aspects salutaires en ce qui concerne le bonheur, le bien\u00eatre et la qualit\u00e9 de vie.<\/p>\n\n\n\n<p>L\u2019all\u00e9gresse, l&#8217;optimisme, l&#8217;humour, l\u2019orgueil, l&#8217;espoir, etc&#8230; sont des exemples d&#8217;\u00e9motions positives, qui, si on les travail, peuvent nous rendre plus heureux et en meilleur forme.<\/p>\n\n\n\n<div class=\"wp-block-image Psychologie positive wp-image-5961 size-full\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"352\" src=\"https:\/\/healthbrain.wpengine.com\/wp-content\/uploads\/2016\/05\/Psicolog\u00eda-positiva.-peque\u00f1os-placeres.jpg\" alt=\"Psychologie positive\" class=\"wp-image-5961\" srcset=\"https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/05\/Psicolog\u00eda-positiva.-peque\u00f1os-placeres.jpg 580w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/05\/Psicolog\u00eda-positiva.-peque\u00f1os-placeres-300x182.jpg 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption><span style=\"color: #999999;\">Psychologie positive, les petits plaisir<\/span><\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Filtrage_Selectif_pourquoi_tendons-nous_a_nous_souvenir_des_choses_negatives\"><\/span><strong>Filtrage&nbsp;S\u00e9lectif&nbsp;: pourquoi tendons-nous \u00e0 nous souvenir des choses n\u00e9gatives ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Bon, il est vrai que souvent dans notre vie de tous les jours <strong>les choses positives sont oubli\u00e9es,&nbsp;<\/strong>ou passent inaper\u00e7ues dans notre esprit et que nous nous <strong>souvenons plus des choses n\u00e9gatives :&nbsp;<\/strong>&#8220;il y avait des bouchons sur la route&#8221; &#8220;l&#8217;eau de la douche \u00e9tait gel\u00e9e ce matin&#8221; &#8220;j&#8217;ai encore grossi, je suis un boudin&#8221; &#8220;je me suis disput\u00e9 avec mon coll\u00e8gue&#8221; etc&#8230; Par contre, on oublie souvent les &#8220;petits plaisirs&#8221; de notre quotidien : un bon repas, une conversation agr\u00e9able, une bonne douche chaude.<\/p>\n\n\n\n<p>Cette tendance que la majorit\u00e9 d&#8217;entre nous a de pr\u00eater plus attention et de se <strong>rappeler&nbsp;<\/strong>mieux les&nbsp;<strong>choses n\u00e9gatives&nbsp;<\/strong>que les choses positives s&#8217;appelle&nbsp;<em>&#8220;le filtrage&nbsp;s\u00e9lectif&#8221;.<\/em><\/p>\n\n\n\n<p>Certains experts consid\u00e8rent que le filtrage s\u00e9lectif est un m\u00e9canisme d&#8217;adaptation, dans le sens que les situations&nbsp;n\u00e9gatives que nous vivons n\u00e9cessitent une r\u00e9ponse afin d&#8217;\u00e9viter de revivre ses m\u00eames situations. Au contraire, les <strong>situations positives ne mettent pas en danger notre survie et donc ne n\u00e9cessite pas de r\u00e9ponse de notre part,<\/strong>&nbsp;c&#8217;est pourquoi elles passent &#8220;inaper\u00e7ues&#8221; de notre attention et de notre m\u00e9moire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Trucs_de_psychologie_positive_exercices_et_techniques_pour_augmenter_les_emotions_positives\"><\/span>Trucs de psychologie positive : exercices et techniques pour augmenter les \u00e9motions positives<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Truc_de_psychologie_positive_petits_plaisirs\"><\/span><strong>1. Truc de psychologie positive : petits plaisirs<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>L&#8217;exercice consiste \u00e0 noter dans un <strong>&#8220;journal des plaisirs&#8221;&nbsp;<\/strong>tous les moments et toutes les situations dans lesquels vous profitez, vous vous sentez bien ou lorsque ce que vous faites vous plait.<\/p>\n\n\n\n<p>Par exemple, certains d&#8217;entre vous profitent quand ils lisent un bon livre, en choisissant un coin tranquille et en profitant de leur lecture qui leur g\u00e9n\u00e8re du bien-\u00eatre. Demandez-vous ce que vous ressentez lors de diverses activit\u00e9s, et notez-le.<\/p>\n\n\n\n<p>D&#8217;autres prendront du plaisir en mangeant du chocolat. Dans ce cas, l&#8217;id\u00e9e est que vous d\u00e9dicaciez du temps et de l&#8217;espace pour profiter pleinement de ce petit plaisir, qui peut recharger vos batteries et vous faire sentir mieux. Si en plus vous vous centrez sur les sensations que provoque le fait de manger ce chocolat, sa douceur, son go\u00fbt et sa texture&#8230; cela augmentera l&#8217;effet de bien-\u00eatre qu&#8217;il vous procurera.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Truc_de_psychologie_positive_vos_forces\"><\/span>2.&nbsp;<strong>Truc de psychologie positive : vos f<\/strong>orces<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Deuxi\u00e8mement, voici une liste des <strong>forces personnelles<\/strong>&nbsp;afin que vous puissiez choisir celles avec lesquelles vous vous identifiez.<\/p>\n\n\n\n<p>L&#8217;objectif est que vous cherchiez vos points forts. Une fois que vous les aurez trouv\u00e9s il vous sera plus facile de les utiliser pour am\u00e9liorer votre quotidien.<\/p>\n\n\n\n<table class=\"wp-block-table\"><tbody><tr><td><strong>1. &nbsp; &nbsp; &nbsp;Sagesse et Connaissances<\/strong><\/td><\/tr><tr><td>Cr\u00e9ativit\u00e9<\/td><td>Penser \u00e0 de nouvelles mani\u00e8res de faire les choses<\/td><\/tr><tr><td>Curiosit\u00e9<\/td><td>Montrer de l&#8217;int\u00e9r\u00eat pour toutes les exp\u00e9riences qui se produisent autour de vous<\/td><\/tr><tr><td>Ouverture d&#8217;esprit<\/td><td>Penser aux choses en profondeur et de tous les points de vue<\/td><\/tr><tr><td>D\u00e9sir d&#8217;apprendre<\/td><td>Chercher le d\u00e9veloppement de nouvelles comp\u00e9tences et de nouvelles aptitudes<\/td><\/tr><tr><td>Perspective<\/td><td>\u00catre capable de proportionner des conseils ad\u00e9quats aux autres personnes<\/td><\/tr><tr><td><strong>2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong><strong>Bravoure<\/strong><\/td><\/tr><tr><td>Courage<\/td><td>Ne pas se d\u00e9composer face aux menaces, aux difficult\u00e9s et \u00e0 la douleur<\/td><\/tr><tr><td>Persistance<\/td><td>Finir ce qui a \u00e9t\u00e9 entreprit<\/td><\/tr><tr><td>Int\u00e9grit\u00e9\/Authenticit\u00e9<\/td><td>Dire la v\u00e9rit\u00e9 et se pr\u00e9senter face aux autres avec sinc\u00e9rit\u00e9<\/td><\/tr><tr><td>Vitalit\u00e9<\/td><td>Faire preuve d&#8217;\u00e9nergie et d&#8217;excitation<\/td><\/tr><tr><td><strong>3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>Humanit\u00e9<\/strong><\/td><\/tr><tr><td>Amour<\/td><td>Donner de la valeur aux relations intimes&nbsp;avec les autres<\/td><\/tr><tr><td>Bont\u00e9<\/td><td>\u00catre serviable et aider les autres<\/td><\/tr><tr><td>Intelligence sociale<\/td><td>\u00catre conscient de ses motivations et de ses sentiments ainsi que de ceux des autres<\/td><\/tr><tr><td><strong>4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>Justice<\/strong><\/td><\/tr><tr><td>Civisme et Travail en \u00e9quipe<\/td><td>Travailler bien en tant que membre d&#8217;un groupe ou d&#8217;une \u00e9quipe<\/td><\/tr><tr><td>Impartialit\u00e9\/Justice<\/td><td>Traiter tout le monde de la m\u00eame fa\u00e7on en accord avec les notions de justice et d&#8217;\u00e9quit\u00e9<\/td><\/tr><tr><td>Leadership<\/td><td>Organiser des activit\u00e9s de groupe et r\u00e9ussir \u00e0 les mener \u00e0 bien<\/td><\/tr><tr><td><strong>5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Temp\u00e9rance<\/strong><strong>\/Mod\u00e9ration<\/strong><\/td><\/tr><tr><td>Capacit\u00e9 \u00e0 pardonner<\/td><td>Pardonner \u00e0 ceux qui nous ont fait du mal<\/td><\/tr><tr><td>Humilit\u00e9\/Modestie<\/td><td>Laisser les succ\u00e8s parler d&#8217;eux-m\u00eames<\/td><\/tr><tr><td>Prudence<\/td><td>\u00catre pr\u00e9cautionneux pour les d\u00e9cisions personnelles, ne pas faire ou dire des choses qui pourraient \u00eatre regrett\u00e9es<\/td><\/tr><tr><td>Autor\u00e9gulation<\/td><td>R\u00e9guler ce qui est ressenti et ce qui est fait<\/td><\/tr><tr><td><strong>6.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>Transcendance<\/strong><\/td><\/tr><tr><td>Appr\u00e9cier la beaut\u00e9<\/td><td>Savoir percevoir et appr\u00e9cier la beaut\u00e9 et l&#8217;excellence dans tous les domaines de la vie<\/td><\/tr><tr><td>Gratitude<\/td><td>\u00catre conscient et reconnaissant des bonnes choses qui se produisent<\/td><\/tr><tr><td>Esp\u00e9rance<\/td><td>Esp\u00e9rer le meilleur et travailler pour l&#8217;obtenir<\/td><\/tr><tr><td>Humour<\/td><td>Aimer rire et s&#8217;amuser, rendre les autres souriants<\/td><\/tr><tr><td>Spiritualit\u00e9<\/td><td>Avoir des croyances coh\u00e9rentes sur quelque chose de plus grand que soi-m\u00eame et sur le sens de la vie<\/td><\/tr><\/tbody><\/table>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Truc_de_psychologie_positive_appui_social\"><\/span>3.&nbsp;<strong>Truc de psychologie positive : appui social<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Un exercice qui favorise les \u00e9motions positives est la recherche d&#8217;appuis sociaux. Au travers des relations que nous avons avec les autres personnes nous arrivons \u00e0 sortir la t\u00eate de l&#8217;eau, \u00e0 mettre de l&#8217;ordre dans le chaos \u00e9motionnel que nous pouvons avoir dans la t\u00eate, \u00e0 \u00e9couter un point de vue diff\u00e9rent et \u00e0 promouvoir des \u00e9motions positives comme la reconnaissance, le pardon, la sinc\u00e9rit\u00e9, l&#8217;affection, etc&#8230;<\/p>\n\n\n\n<div class=\"wp-block-image Psychologie positive wp-image-6137 size-full\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"526\" height=\"350\" src=\"https:\/\/healthbrain.wpengine.com\/wp-content\/uploads\/2016\/05\/psicologia-positiva.-apoyo-social.jpg\" alt=\"Psychologie positive\" class=\"wp-image-6137\" srcset=\"https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/05\/psicologia-positiva.-apoyo-social.jpg 526w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/05\/psicologia-positiva.-apoyo-social-300x200.jpg 300w\" sizes=\"auto, (max-width: 526px) 100vw, 526px\" \/><figcaption><span style=\"color: #999999;\">Truc de psychologie positive, le soutien social pour \u00eatre plus heureux<\/span><\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4Truc_de_psychologie_positive_exercice\"><\/span>4.<strong>Truc de psychologie positive : exercice<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les experts soutiennent que l&#8217;activit\u00e9 physique mod\u00e9r\u00e9e est li\u00e9 au fait d&#8217;avoir un organisme plus sain, d&#8217;augmenter l&#8217;esp\u00e9rance de vie, le nombre d&#8217;\u00e9motions positives, l&#8217;estime de soi ainsi que le nombre de relations sociale et enfin d&#8217;am\u00e9liorer aussi la qualit\u00e9 du sommeil. Pour tous cela, il est recommand\u00e9 d&#8217;avoir une activit\u00e9 physique r\u00e9guli\u00e8re afin d&#8217;am\u00e9liorer notre qualit\u00e9 de vie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_Truc_de_psychologie_positive_relations_sexuelles\"><\/span>5.&nbsp;<strong>Truc de psychologie positive : relations sexuelles<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Augmenter l&#8217;activit\u00e9 sexuelle est plus efficace que les traitements pharmacologiques pour combattre la d\u00e9pression et encourager les \u00e9motions positives. Le sexe lib\u00e8re de l&#8217;endorphine, cr\u00e9ant un \u00e9tat d&#8217;euphorie qui se traduit en un puissant sentiment de bien-\u00eatre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_Truc_de_psychologie_positive_intensifier_le_niveau_dactivite\"><\/span>6.&nbsp;<strong>Truc de psychologie positive :&nbsp;intensifier le niveau d&#8217;activit\u00e9<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les experts affirment que des niveaux mod\u00e9r\u00e9s d&#8217;activit\u00e9s agr\u00e9ables ont des effets comparables aux antid\u00e9presseurs. Programmez des activit\u00e9s agr\u00e9ables dans votre quotidien.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7_Truc_de_psychologie_positive_reconnaissance\"><\/span>7.&nbsp;<strong>Truc de psychologie positive : reconnaissance<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Pratiquer la reconnaissance est l&#8217;une des choses qui procure le plus de bien-\u00eatre. Parfois, nous ne nous rendons pas compte, mais nous avons toujours quelque chose de quoi \u00eatre reconnaissant. Voici trois exercices qui sont tr\u00e8s utiles pour cultiver vos habitudes de reconnaissance :<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Tenez un <strong>journal de gratitude&nbsp;<\/strong>et chaque nuit, avant d&#8217;aller dormir, notez dedans au moins trois choses pour lesquelles vous vous sentez reconnaissant.<\/li><li>\u00c9crivez une <strong>carte de remerciement&nbsp;<\/strong>\u00e0 une personne sp\u00e9ciale. \u00c9crivez comment vous vous sentez gr\u00e2ce aux &#8220;cadeaux&#8221; qu&#8217;elle vous a fait. Chercher cette personne, et si possible lisez-lui personnellement la carte. Laissez-vous envahir par les sentiments et les \u00e9motions que procure la reconnaissance.<\/li><li><strong>Dites merci<\/strong>&nbsp;\u00e0 chaque instant. \u00c9tablissez l&#8217;habitude mentale d&#8217;\u00eatre toujours reconnaissant et en tout instant. Cherchez activement les intentions et les actions des autres personnes qui cherchent \u00e0 vous aider et\/ou \u00e0 vous faire sentir bien, et remerciez-les&#8230;\n<p style=\"text-align: left;\">&#8220;Source&nbsp;: Beatriz Marques, psychologue de Cognifit experte de l\u2019anxi\u00e9t\u00e9 et du stress.&#8221;<\/p>\n<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Quelle id\u00e9e vous faites-vous du bonheur ? Qu&#8217;est-ce qui selon vous vous rend heureux ? Il est possible que beaucoup d&#8217;entre vous ont pens\u00e9s \u00e0 [&#8230;]<\/p>\n","protected":false},"author":28,"featured_media":11195,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3488,3490,10777],"tags":[3719,791,4529,799,3928,4528,3722,4531,4530],"class_list":["post-10634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosite","category-sante","category-sports-et-athletisme","tag-bonheur","tag-dopamine","tag-emotions-positives","tag-intelligence","tag-intelligence-emotionnelle","tag-les-cles-du-bonheur","tag-psychologie-positive","tag-secret-du-bonheur","tag-trucs-de-psychologie-positive"],"_links":{"self":[{"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/posts\/10634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/comments?post=10634"}],"version-history":[{"count":0,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/posts\/10634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/media\/11195"}],"wp:attachment":[{"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/media?parent=10634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/categories?post=10634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yourbrain.health\/fr\/wp-json\/wp\/v2\/tags?post=10634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}