{"id":25481,"date":"2018-06-05T10:42:20","date_gmt":"2018-06-05T10:42:20","guid":{"rendered":"https:\/\/healthbrain.wpengine.com\/?p=25481"},"modified":"2020-10-19T19:45:14","modified_gmt":"2020-10-19T19:45:14","slug":"psicologia-educativa-psicologo-educacional","status":"publish","type":"post","link":"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/","title":{"rendered":"Psicolog\u00eda Educativa: Gu\u00eda completa \u00bfCual es el papel del psic\u00f3logo educacional?"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>Una completa gu\u00eda sobre la psicolog\u00eda educativa o educacional: Qu\u00e9 es, cual es su objetivo, los or\u00edgenes, autores y teor\u00edas influyentes, \u00e1reas de aplicaci\u00f3n. Descubre las funciones, las salidas profesionales y el papel del psic\u00f3logo educativo. \u00bfC\u00f3mo es el perfil de un psic\u00f3logo educacional?<\/strong>&nbsp;\u00a1Aqu\u00ed encontrar\u00e1s toda la informaci\u00f3n acerca de esta rama de la Psicolog\u00eda! Si tienes cualquier pregunta puedes dejarnos tu comentario abajo, y te responderemos.&nbsp;<\/em><\/p>\n<div id=\"attachment_25737\" style=\"width: 1010px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-25737\" class=\"size-full wp-image-25737\" src=\"https:\/\/healthbrain.wpengine.com\/wp-content\/uploads\/2018\/05\/Psicolog\u00eda-educativa-y-psicologo-educacional.jpg\" alt=\"Psicolog\u00eda educativa y psic\u00f3logo educacional\" width=\"1000\" height=\"667\" srcset=\"https:\/\/yourbrain.health\/wp-content\/uploads\/2018\/05\/Psicolog\u00eda-educativa-y-psicologo-educacional.jpg 1000w, https:\/\/yourbrain.health\/wp-content\/uploads\/2018\/05\/Psicolog\u00eda-educativa-y-psicologo-educacional-300x200.jpg 300w, https:\/\/yourbrain.health\/wp-content\/uploads\/2018\/05\/Psicolog\u00eda-educativa-y-psicologo-educacional-768x512.jpg 768w, https:\/\/yourbrain.health\/wp-content\/uploads\/2018\/05\/Psicolog\u00eda-educativa-y-psicologo-educacional-640x427.jpg 640w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><p id=\"caption-attachment-25737\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Psicolog\u00eda educativa y psic\u00f3logo educacional<\/span><\/p><\/div>\n<p>La psicolog\u00eda se encarga de estudiar cient\u00edficamente la conducta humana y los procesos mentales. Son varias las distintas subdisciplinas de la psicolog\u00eda que centran su enfoque en alg\u00fan aspecto particular de la psique humana, con el fin de entender mejor nuestra <a href=\"https:\/\/healthbrain.wpengine.com\/es\/conducta\/\" target=\"_blank\" rel=\"noopener noreferrer\">conducta<\/a> y proporcionar herramientas para mejorar el bienestar de cada individuo.<\/p>\n<p>Una de estas subdisciplinas es la&nbsp;<strong>psicolog\u00eda educativa<\/strong>&nbsp;(tambi\u00e9n llamada&nbsp;<em>psicolog\u00eda educacional<\/em>)<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04ae9eb152f\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04ae9eb152f\" checked aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#%C2%BFQue_es_la_Psicologia_Educativa_o_educacional_Definicion_y_concepto\" >\u00bfQu\u00e9 es la Psicolog\u00eda Educativa o educacional? Definici\u00f3n y concepto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#%C2%BFCuando_aparece_o_surge_la_psicologia_educativa\" >\u00bfCuando aparece o surge la psicolog\u00eda educativa?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#Modelos_de_estudio_mas_importantes_en_Psicologia_Educativa\" >Modelos de estudio m\u00e1s importantes en Psicolog\u00eda Educativa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#Perfil_del_psicologo_educacional\" >Perfil del psic\u00f3logo educacional<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#Nuevas_tecnologias_en_la_psicologia_educativa\" >Nuevas tecnolog\u00edas en la psicolog\u00eda educativa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#Areas_de_aplicacion_de_la_Psicologia_Educativa\" >\u00c1reas de aplicaci\u00f3n de la Psicolog\u00eda Educativa<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#1-_Intervencion_ante_las_necesidades_educativas_de_los_alumnos\" >1- Intervenci\u00f3n ante las necesidades educativas de los alumnos:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#2-_Funciones_ligadas_a_la_orientacion_asesoramiento_profesional_y_asesoramiento_vocacional\" >2- Funciones ligadas a la orientaci\u00f3n, asesoramiento profesional y asesoramiento vocacional:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#3-_Funciones_preventivas\" >3- Funciones preventivas:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#4-_Intervencion_en_la_mejora_del_acto_educativo\" >4- Intervenci\u00f3n en la&nbsp;mejora del acto educativo:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#5-_Formacion_y_Asesoramiento_Familiar\" >5- Formaci\u00f3n y Asesoramiento Familiar:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#6-_Intervencion_socioeducativa\" >6- Intervenci\u00f3n socioeducativa:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/yourbrain.health\/es\/psicologia-educativa-psicologo-educacional\/#7-_Investigacion_y_docencia\" >7- Investigaci\u00f3n y docencia:<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_la_Psicologia_Educativa_o_educacional_Definicion_y_concepto\"><\/span>\u00bfQu\u00e9 es la Psicolog\u00eda Educativa o educacional? Definici\u00f3n y concepto<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La Psicolog\u00eda Educativa, tambi\u00e9n denominada psicolog\u00eda educacional se encarga de profundizar en el aprendizaje y en los m\u00e9todos educativos m\u00e1s id\u00f3neos para que los estudiantes puedan desarrollar sus <a href=\"https:\/\/www.cognifit.com\/es\/habilidades-cognitivas\" target=\"_blank\" rel=\"noopener noreferrer\">habilidades cognitivas<\/a>.<\/p>\n<p>A trav\u00e9s de la psicolog\u00eda educativa se estudian las formas en que se lleva a cabo el aprendizaje humano, especialmente en el contexto de los centros educativos. Esta subdisciplina analiza los modos en que aprendemos y ense\u00f1amos y trata de aumentar la efectividad de las distintas intervenciones educativas a fin de optimizar el proceso. Tambi\u00e9n trata de aplicar los principios y leyes de la psicolog\u00eda social a las instituciones y organizaciones educativas.<\/p>\n<p>Dicho de otro modo, <strong>el objeto de estudio de la psicolog\u00eda educativa es el aprendizaje de los estudiantes y los distintos aspectos que modulan&nbsp;su desarrollo cognitivo<\/strong>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuando_aparece_o_surge_la_psicologia_educativa\"><\/span>\u00bfCuando aparece o surge la psicolog\u00eda educativa?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El <strong>surgimiento<\/strong> de&nbsp;la psicolog\u00eda educativa se puede delimitar en cuatro fases:<\/p>\n<ol>\n<li><strong>Primera fase<\/strong>: En la \u00e9poca de 1880 y 1920 donde la preocupaci\u00f3n individual y el tratamiento de los ni\u00f1os problem\u00e1ticos era un tema de gran inter\u00e9s<\/li>\n<li><strong>Segunda fase<\/strong>: Se podr\u00eda ubicar en los a\u00f1os 1920 y 1955 donde se proliferan los servicios psicol\u00f3gicos para tratar problemas infantiles dentro y fuera de los centros educativos<\/li>\n<li><strong>Tercera fase<\/strong>: Se encuentra en los a\u00f1os 1955 y 1970 donde la necesidad de formar a profesores con conocimientos en psicolog\u00eda comenz\u00f3 a ser una necesidad al igual que integrar en la metodolog\u00eda did\u00e1ctica estos conocimientos psicol\u00f3gicos.<\/li>\n<li><strong>Cuarta fase<\/strong>: Por \u00faltimo, es a partir del a\u00f1o 1970, donde se toma en consideraci\u00f3n todo lo anterior y gracias a las teor\u00edas cognitivas, ecol\u00f3gicas, sociales y organizacionales se asienta la psicolog\u00eda educativa.<\/li>\n<\/ol>\n<p>Cuando la psicolog\u00eda surge como disciplina se aplican los m\u00e9todos cient\u00edficos como la observaci\u00f3n y experimentaci\u00f3n en los \u00e1mbitos educativos. Los primeros a\u00f1os los psic\u00f3logos educativos mediante una serie de conferencias que publicaron en el <strong>a\u00f1o 1899<\/strong>, mencionan que la psicolog\u00eda es una ciencia y ense\u00f1ar es un arte. Por lo que all\u00ed est\u00e1 escrito, es considerado el&nbsp;<strong>primer manual de la psicolog\u00eda educativa<\/strong>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Modelos_de_estudio_mas_importantes_en_Psicologia_Educativa\"><\/span>Modelos de estudio m\u00e1s importantes en Psicolog\u00eda Educativa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En el contexto escolar, la psicolog\u00eda educativa<strong>&nbsp;investiga los mejores m\u00e9todos y planes de estudio que permitan mejorar el modelo educativo y la gesti\u00f3n de los centros<\/strong>.<\/p>\n<p>Siendo su objetivo la mejor comprensi\u00f3n de los elementos y caracter\u00edsticas que influyen en el aprendizaje durante la infancia, la adolescencia, la adultez y la vejez,&nbsp;los psic\u00f3logos educativos son los encargados de&nbsp;<strong>elaborar e implementar distintas teor\u00edas sobre el desarrollo humano&nbsp;<\/strong>que ayuden a comprender los distintos procesos y contextos en que se produce el aprendizaje.<\/p>\n<p>A lo largo del pasado siglo, varios autores<strong>&nbsp;propusieron modelos y teor\u00edas para explicar el modo en que los humanos nos relacionamos con el conocimiento<\/strong>. Estas teor\u00edas han servido para influir en los enfoques y m\u00e9todos que usa la psicolog\u00eda educativa:<\/p>\n<ul>\n<li>El psic\u00f3logo suizo&nbsp;<strong><a title=\"Teor\u00eda de Piaget: Etapas del desarrollo cognitivo del ni\u00f1o \u00bfTu hijo evoluciona seg\u00fan su edad?\" href=\"https:\/\/healthbrain.wpengine.com\/es\/teoria-piaget-etapas-desarrollo-ninos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Jean Piaget<\/a>&nbsp;<\/strong>(1896-1980) ha ejercido una influencia decisiva para la psicolog\u00eda educativa. Su teor\u00eda ahond\u00f3 en los <strong>estad\u00edos<\/strong> por los que pasan los ni\u00f1os&nbsp;hasta que logran desarrollar el pensamiento l\u00f3gico abstracto en torno a los once a\u00f1os de edad. Es uno de los m\u00e1ximos referentes en el campo de la psicolog\u00eda del desarrollo.<\/li>\n<li><em>\u00bfEn qu\u00e9 grado influye la cultura y la sociedad al desarrollo cognitivo de los ni\u00f1os?&nbsp;<\/em>Esta es la pregunta que se plante\u00f3 el psic\u00f3logo ruso&nbsp;<strong>Lev Vygostky<\/strong>&nbsp;(1896-1934). Vygostky investig\u00f3 acerca de la influencia de los distintos \u00e1mbitos sociales en los que se producen interacciones que llevan al ni\u00f1o a asimilar e interiorizar algunas pautas de comportamiento.<br \/>\nSus conceptos, como los de <em><strong>zona de desarrollo proximal<\/strong><\/em> y <em><strong>aprendizaje por andamiaje<\/strong><\/em>, est\u00e1n todav\u00eda vigentes.<\/li>\n<li><strong><a href=\"https:\/\/healthbrain.wpengine.com\/es\/albert-bandura-teoria-de-aprendizaje-social-timplicaciones-educativas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Albert Bandura<\/a>&nbsp;<\/strong>(nacido en 1925) tambi\u00e9n desarroll\u00f3 conceptos clave para el&nbsp;sociocognitivismo y para la psicolog\u00eda educativa. Bandura analiz\u00f3 la \u00edntima relaci\u00f3n entre las variables contextuales y sociales con los procesos de aprendizaje. Adem\u00e1s, fue el autor de conceptos de gran inter\u00e9s como el del&nbsp;<strong>autoconcepto<\/strong>.<\/li>\n<\/ul>\n<p>Existen otros constructos te\u00f3ricos que tambi\u00e9n han aportado grandes conocimientos al \u00e1mbito de la psicolog\u00eda educativa. Por ejemplo, la<strong>&nbsp;Teor\u00eda del desarrollo moral&nbsp;<\/strong>de <strong>Lawrence<\/strong> <strong>Kohlberg<\/strong> y el <strong>Modelo de desarrollo infantil<\/strong>&nbsp;propuesto por <strong>Rudolf Steiner<\/strong>.<\/p>\n<p>Adem\u00e1s de psic\u00f3logos que aportaron su granito de arena a la psicolog\u00eda educacional, tambi\u00e9n es necesario citar otros autores y figuras con un peso decisivo y que sembraron de conocimientos y reflexiones esta subdisciplina.<\/p>\n<ul>\n<li>Por ejemplo, es destacable el caso de la pedagoga y psiquiatra italiana&nbsp;<strong>Mar\u00eda Montessori<\/strong>, que logr\u00f3 sentar unas bases totalmente novedosas en la pedagog\u00eda de inicios del siglo XX. El <a title=\"M\u00e9todo Montessori: Descubre todo sobre esta alternativa pedag\u00f3gica. Qu\u00e9 es, ejercicios y t\u00e9cnicas para aplicarlo\u2026\" href=\"https:\/\/healthbrain.wpengine.com\/es\/metodo-montessori\/\" target=\"_blank\" rel=\"noopener noreferrer\">M\u00e9todo Montessori<\/a> removi\u00f3 los cimientos de la pedagog\u00eda cl\u00e1sica planteando un m\u00e9todo pedag\u00f3gico en el que presentaba cuatro pilares fundamentales para la educaci\u00f3n de los estudiantes.<\/li>\n<\/ul>\n<p>Estos cuatro pilares en que se basa cualquier proceso de aprendizaje son:<strong>&nbsp;el adulto<\/strong>,&nbsp;<strong>la mente del estudiante<\/strong>,&nbsp;<strong>el ambiente de aprendizaje<\/strong>&nbsp;y los <strong>per\u00edodos sensibles<\/strong>&nbsp;en los que el ni\u00f1o est\u00e1 m\u00e1s receptivo a aprender nuevos conocimientos o habilidades. Los psic\u00f3logos educativos deben conocer el<a href=\"https:\/\/healthbrain.wpengine.com\/es\/aprendizaje-cognitivo-tipos-aprendizaje\/\" target=\"_blank\" rel=\"noopener noreferrer\"> aprendizaje cognitivo y los tipos de aprendizajes<\/a> que existen para poder contribuir positivamente en el desarrollo infantil y juvenil.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Perfil_del_psicologo_educacional\"><\/span>Perfil del psic\u00f3logo educacional<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>La psicolog\u00eda educativa estudia los factores sociales y culturales<\/strong>&nbsp;aplicando diferentes teor\u00edas. En la actualidad, esta subdisciplina contin\u00faa estudiando este proceso de aprendizaje del alumno para beneficiarlo pese a este factor importante que est\u00e1 haciendo que el estudiante se vuelva ocioso.<\/p>\n<p>Ninguna otra disciplina conoce mejor a las personas que est\u00e1n en la etapa escolar sea ni\u00f1o, adolescente o adulto, porque es a la psicolog\u00eda educativa a quien le corresponde intervenir en la prevenci\u00f3n de problemas que est\u00e9n obstaculizando el proceso de ense\u00f1anza-aprendizaje dise\u00f1ando planes de intervenci\u00f3n, promoviendo criterios metodol\u00f3gicos, sistemas de evaluaci\u00f3n, entre otros; haciendo uso de las&nbsp;<strong>herramientas que se adapten a la etapa del estudiante<\/strong>.<\/p>\n<p>Entre sus funciones espec\u00edficas, destaca la realizaci\u00f3n de una&nbsp;<strong>evaluaciones psicol\u00f3gicas completas&nbsp;<\/strong>al alumnado, con el objetivo de detectar necesidades educativas especiales, problemes sociales y\/o emocionales o dificultades de aprendizaje espec\u00edficas como la dislexia. Los psic\u00f3logos pueden trabajar directamente con el ni\u00f1o o indirectamente, a trav\u00e9s de su trabajo con los padres, maestros y otros profesionales.<\/p>\n<p>En el trabajo directo, la evaluaci\u00f3n puede incluir la observaci\u00f3n del comportamiento del ni\u00f1o, por medio de entrevistas y pruebas psicol\u00f3gicas. A partir de esta evaluaci\u00f3n, el psic\u00f3logo educativo plantea una serie recomendaciones que pueden incluir asesoramiento, sesiones de terapia familiar, la elaboraci\u00f3n de un itinerario educativo m\u00e1s apropiado para el ni\u00f1o o intervenci\u00f3n para trabajar los problemas de comportamiento.<\/p>\n<p>En su trabajo indirecto, los psic\u00f3logos educativos contribuyen con sus opiniones y resultados en el trabajo de otros profesionales, incluidos educadores, trabajadores sociales, asesores m\u00e9dicos y visitadores de salud.<\/p>\n<p>Otra funci\u00f3n espec\u00edfica de los psic\u00f3logos educativos es la&nbsp;<strong>formaci\u00f3n de docentes<\/strong>&nbsp;en diferentes t\u00e9cnicas para ayudar al alumnado con dificultades de aprendizaje y\/o problemas de conducta. Adem\u00e1s, pueden organizar cursos y talleres para padres, profesores u otros profesionales sobre temas como el control del estr\u00e9s, el acoso escolar, dificultades espec\u00edficas de aprendizaje y control de conducta.<\/p>\n<p>Algunos psic\u00f3logos educativos est\u00e1n involucrados en trabajos de&nbsp;<strong>investigaci\u00f3n<\/strong>, ayudando a crear pol\u00edticas eficaces de educaci\u00f3n. Por ejemplo, pueden evaluar la eficacia de la pol\u00edtica de la escuela sobre el <a title=\"Consecuencias del bullying o acoso escolar en ni\u00f1os \u00bfSe pueden reparar los peque\u00f1os corazones?\" href=\"https:\/\/healthbrain.wpengine.com\/es\/consecuencias-bullying\/\" target=\"_blank\" rel=\"noopener noreferrer\">acoso escolar o bullying<\/a>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Nuevas_tecnologias_en_la_psicologia_educativa\"><\/span>Nuevas tecnolog\u00edas en la psicolog\u00eda educativa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Un<a href=\"https:\/\/www.researchandmarkets.com\/research\/2ljvvr\/global_k12?w=5\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">&nbsp;nuevo informe de investigaci\u00f3n de mercado<\/a>&nbsp;perfila a&nbsp;CogniFit&nbsp;como una de las&nbsp;soluciones tecnol\u00f3gicas clave en la psicolog\u00eda educativa.<\/p>\n<p>CogniFit permite&nbsp;<strong>ofrecer servicios m\u00e1s competitivos<\/strong>&nbsp;a los psic\u00f3logos educacionales y a los alumnos, as\u00ed como puede ayudar a prevenir el fracaso escolar, abordar la diversidad en el aula, nuevas estrategias de educaci\u00f3n, etc.<\/p>\n<p>La alt\u00edsimo calidad de las bater\u00edas cl\u00ednicas, su fiabilidad, y la seguridad de las escuelas de contar con la \u00faltima tecnolog\u00eda disponible, ha ayudado a que&nbsp;<strong>CogniFit se posicione, una vez m\u00e1s, como<a href=\"https:\/\/www.cognifit.com\/es\/plataforma-educativa\" target=\"_blank\" rel=\"noopener noreferrer\">&nbsp;tecnolog\u00eda l\u00edder en el campo de la neuroeducaci\u00f3n<\/a><\/strong><a href=\"https:\/\/www.cognifit.com\/es\/plataforma-educativa\" target=\"_blank\" rel=\"noopener noreferrer\">.<\/a><\/p>\n<p>CogniFit pone a disposici\u00f3n del sistema educativo&nbsp;<a href=\"https:\/\/www.cognifit.com\/es\/evaluacion-cognitiva\/test-cognitivo\" target=\"_blank\" rel=\"noopener noreferrer\">bater\u00edas de evaluaci\u00f3n neuropsicol\u00f3gica<\/a>&nbsp;y programas personalizados de<a href=\"https:\/\/www.cognifit.com\/es\/entrenamiento-cerebral-personalizado\" target=\"_blank\" rel=\"noopener noreferrer\">&nbsp;entrenamiento cerebral<\/a>&nbsp;dirigidos a mejorar los procesos cognitivos implicados en el aprendizaje.<\/p>\n<blockquote><p><strong>Carlos Rodr\u00edguez<i>,&nbsp;<\/i>CTO de CogniFit, expone<\/strong><i>&nbsp;\u201cCada vez hay m\u00e1s sectores conscientes de la necesidad de aplicar soluciones tecnol\u00f3gicas. Un ejemplo de esto, son los m\u00faltiples centro educativos y psic\u00f3logos educativos que han incorporado la tecnolog\u00eda a la ense\u00f1anza y reclaman recursos cient\u00edficos de <a title=\"Todo sobre la neuroeducaci\u00f3n: Qu\u00e9 es, para qu\u00e9 sirve, y c\u00f3mo aplicarla en la escuela y en casa\" href=\"https:\/\/healthbrain.wpengine.com\/es\/neuroeducacion-que-es-y-para-que-sirve\/\" target=\"_blank\" rel=\"noopener noreferrer\">neuroeducaci\u00f3n<\/a>.\u201d &nbsp;<\/i><\/p><\/blockquote>\n<p>La demanda de herramientas innovadoras que permitan realizar<strong>&nbsp;evaluaciones neuropsicol\u00f3gicas digitalizadas (online) y generar informes automatizados<\/strong>&nbsp;con el perfil cognitivo de cada alumno se convierte en una&nbsp;<strong>necesidad creciente<\/strong>. El n\u00famero de colaboraciones entre escuelas y CogniFit est\u00e1 creciendo r\u00e1pidamente.<\/p>\n<div id=\"attachment_19627\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.cognifit.com\/es\/entrenamiento-cerebral-personalizado\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19627\" class=\"Entrenamiento cerebral wp-image-19627 size-full\" title=\"Entrenamiento cerebral\" src=\"https:\/\/healthbrain.wpengine.com\/wp-content\/uploads\/2018\/01\/ES-Entrenamiento-Cerebral-Video-Ok.gif\" alt=\"Entrenamiento cognitivo\" width=\"600\" height=\"360\"><\/a><p id=\"caption-attachment-19627\" class=\"wp-caption-text\"><strong>CogniFit programa cient\u00edfico l\u00edder en <a href=\"https:\/\/www.cognifit.com\/es\/evaluacion-cognitiva\/test-cognitivo\" target=\"_blank\" rel=\"noopener noreferrer\">evaluaci\u00f3n cognitiva<\/a> y <a href=\"https:\/\/Entrenamiento cerebral\" target=\"_blank\" rel=\"noopener noreferrer\">entrenamiento cerebral<\/a> <\/strong>online adaptado a las necesidades cognitivas espec\u00edficas de ni\u00f1os y j\u00f3venes. Descubre el estado estado cognitivo de los alumnos menos de 30-40 minutos. CogniFit es la herramienta cl\u00ednica mas utilizada y recomendada por profesionales.<\/p><\/div>\n<p><strong>El IoT (Internet of Things) est\u00e1 transformando la psicolog\u00eda de la educaci\u00f3n<\/strong>. El monitoreo remoto de la salud o evoluci\u00f3n cognitiva de los alumnos a trav\u00e9s de&nbsp;<strong>CogniFit<\/strong>, garantiza una mejor atenci\u00f3n al al alumnado y puede ayudar a&nbsp;<strong>minimizar el fracaso escolar, a reducir tiempo, espacio y costes<\/strong>.<\/p>\n<p>Las nuevas evaluaciones cognitivas computarizadas y las&nbsp;<a href=\"https:\/\/www.cognifit.com\/es\/plataforma-educativa\" target=\"_blank\" rel=\"noopener\">tecnolog\u00edas de aprendizaje que ofrece CogniFit&nbsp;<\/a>se han convertido en un apoyo fundamental para los psic\u00f3logos y centros educativos.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Areas_de_aplicacion_de_la_Psicologia_Educativa\"><\/span>\u00c1reas de aplicaci\u00f3n de la Psicolog\u00eda Educativa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El profesional de la psicolog\u00eda educativa interviene en los \u00e1mbitos personal, familiar, organizacional, institucional, socio-comunitario y educativo en general; con Educandos, receptores del proceso educativo, y Agentes Educativos, intervinientes directa o indirectamente en el proceso educativo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"1-_Intervencion_ante_las_necesidades_educativas_de_los_alumnos\"><\/span>1- Intervenci\u00f3n ante las necesidades educativas de los alumnos:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El profesional de la psicolog\u00eda participa en la atenci\u00f3n educativa al desarrollo desde las primeras etapas de la vida, para detectar y prevenir a efectos socio-educativos las discapacidades e inadaptaciones funcionales, ps\u00edquicas y sociales.<\/p>\n<p>Realiza la evaluaci\u00f3n psico-educativa referida a la valoraci\u00f3n de las capacidades personales, grupales e institucionales en relaci\u00f3n a los objetivos de la educaci\u00f3n y tambi\u00e9n al an\u00e1lisis del funcionamiento de las situaciones educativas. Para ello trata de determinar la m\u00e1s adecuada relaci\u00f3n entre las necesidades individuales, grupales o colectivas y los recursos del entorno inmediato, institucional o socio-comunitario requeridos para satisfacer dichas necesidades.<\/p>\n<p>Tambi\u00e9n y ligado al proceso de evaluaci\u00f3n el\/la psic\u00f3logo\/a puede proponer y\/o realizar intervenciones que se refieran a la mejora de las competencias educativas de los alumnos, de las condiciones educativas y al desarrollo de soluciones a las posibles dificultades detectadas en la evaluaci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2-_Funciones_ligadas_a_la_orientacion_asesoramiento_profesional_y_asesoramiento_vocacional\"><\/span>2- Funciones ligadas a la orientaci\u00f3n, asesoramiento profesional y asesoramiento vocacional:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El\/la psic\u00f3logo\/a promueve y participa en la organizaci\u00f3n, planificaci\u00f3n, desarrollo y evaluaci\u00f3n de los procesos de orientaci\u00f3n y asesoramiento profesional y vocacional, tanto en lo que tienen de informaci\u00f3n, asesoramiento y orientaci\u00f3n a los alumnos ante las opciones que deban tomar frente a las distintas posibilidades educativas o profesionales, como en la elaboraci\u00f3n de m\u00e9todos de ayuda para la elecci\u00f3n y de m\u00e9todos de aprendizaje de toma de decisi\u00f3n vocacional. El objetivo general de estos procesos es colaborar en el desarrollo de las competencias de las personas en la clarificaci\u00f3n de sus proyectos personales, vocacionales y profesionales de modo que puedan dirigir su propia formaci\u00f3n y su toma de decisiones.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"3-_Funciones_preventivas\"><\/span>3- Funciones preventivas:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>En la que el\/la psic\u00f3logo\/a interviene proponiendo la introducci\u00f3n de modificaciones del entorno educativo y social que eviten la aparici\u00f3n o aten\u00faen las alteraciones en el desarrollo madurativo, educativo y social.<\/p>\n<p>La prevenci\u00f3n se orienta a proponer las condiciones para un mejor desarrollo de las capacidades educativas y tambi\u00e9n a prevenir las consecuencias que pueden generar la diferencia entre las necesidades educativas de la poblaci\u00f3n y las respuestas que dan los sistemas sociales y educativos; incluye tanto acciones espec\u00edficas para la prevenci\u00f3n de problemas educativos concretos &lt;como son a adaptaci\u00f3n inicial a la escuela, la detecci\u00f3n precoz de alumnos con necesidades educativas especiales, etc) como los aspectos de intervenci\u00f3n desde las primeras etapas mediante t\u00e9cnicas de estimulaci\u00f3n y, ya en las etapas escolares, los procesos dirigidos a permitir a los alumnos afrontar con progresiva autonom\u00eda y competencias eficaces las exigencias de la actividad educativa.<\/p>\n<p>Desde el enfoque preventivo se contemplan intervenciones tanto en asesoramiento a agentes educativos (educadores, padres etc) como en el desarrollo de programas espec\u00edficos: educaci\u00f3n para la salud, educaci\u00f3n afectivo-sexual, prevenci\u00f3n de las drogo-dependencias y de los proyectos ligados en general a la transversalidad (educaci\u00f3n de valores, educaci\u00f3n no sexista).<\/p>\n<h3><span class=\"ez-toc-section\" id=\"4-_Intervencion_en_la_mejora_del_acto_educativo\"><\/span>4- Intervenci\u00f3n en la&nbsp;mejora del acto educativo:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Las funciones ligadas a esta intervenci\u00f3n pretenden la adecuaci\u00f3n de las situaciones educativas a las caracter\u00edsticas individuales y\/o grupales (evolutivas, cognitivas, sociales etc) de los alumnos y viceversa. Estas funciones se realizan a trav\u00e9s de asesoramiento did\u00e1ctico, de la organizaci\u00f3n y planificaci\u00f3n educativa, de programaci\u00f3n, de asesoramiento y actualizaci\u00f3n del educador; y en general se refieren a la intervenci\u00f3n sobre las funciones formativas y educativas que se realizan con el alumno.<\/p>\n<p>El\/la psic\u00f3logo\/a presta apoyo y asesoramiento t\u00e9cnico al educador tanto en:<\/p>\n<p>Su actividad general: adaptaci\u00f3n de la programaci\u00f3n a las caracter\u00edsticas evolutivas psico-sociales y de aprendizaje de los alumnos, organizaci\u00f3n del escenario educativo, m\u00e9todos de ense\u00f1anza-aprendizaje, niveles de concreci\u00f3n curricular, aplicaci\u00f3n de programas psico-educativos concretos etc.<\/p>\n<p>Como en su actuaci\u00f3n educativa con alumnos con necesidades y\/o en situaciones educativas especiales, adecuaciones curriculares y programas individuales, actuaciones compensatorias, diversificaciones y en general procedimientos de atenci\u00f3n a la diversidad.<\/p>\n<p>Igualmente colabora en la formaci\u00f3n permanente y apoyo did\u00e1ctico al educador, aportando su preparaci\u00f3n espec\u00edfica sobre las \u00e1reas evolutivas, cognitivas, afectivas, comportamentales, psicosociales e institucionales.<\/p>\n<p>Tambi\u00e9n son objeto de la intervenci\u00f3n del\/la psic\u00f3logo\/a los fen\u00f3menos institucionales que configuran los centros educativos: la relaci\u00f3n entre los objetivos y las formas organizativas con el funcionamiento real, la mejora eficaz de las relaciones entre los componentes de la instituci\u00f3n educativa etc; as\u00ed presta su colaboraci\u00f3n y apoyo t\u00e9cnico en la elaboraci\u00f3n y desarrollo de proyectos educativos de centro, de proyectos de innovaci\u00f3n curricular, integraci\u00f3n y atenci\u00f3n a la diversidad, nuevas tecnolog\u00edas, compensaci\u00f3n y apoyo educativo, etc; as\u00ed como en los cambios organizativos y metodol\u00f3gicos requeridos por estos proyectos, en la l\u00ednea de hacer competentes a las propias instituciones en la realizaci\u00f3n de los fines que se proponen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"5-_Formacion_y_Asesoramiento_Familiar\"><\/span>5- Formaci\u00f3n y Asesoramiento Familiar:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El\/la psic\u00f3logo\/a act\u00faa promoviendo y organizando la informaci\u00f3n y formaci\u00f3n a madres y padres en una linea de apoyo al desarrollo integral del hijo\/a. Realiza la intervenci\u00f3n para la mejora de las relaciones sociales y familiares, as\u00ed como la colaboraci\u00f3n efectiva entre familias y educadores, promoviendo la participaci\u00f3n familiar en la comunidad educativa, as\u00ed como en los programas, proyectos y actuaciones que el profesional de la psicolog\u00eda educativa desarrolle.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"6-_Intervencion_socioeducativa\"><\/span>6- Intervenci\u00f3n socioeducativa:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El\/la psic\u00f3logo\/a participa en el an\u00e1lisis de la realidad educativa, y de los factores sociales y culturales que influyen en el proceso educativo de la comunidad concreta, interviene en la prevenci\u00f3n socioeducativa, impulsa la cooperaci\u00f3n y coordinaci\u00f3n de los servicios, instituciones y organizaciones sociales del entorno. En resumen, interviene en las relaciones entre las actividades educativas y la comunidad donde tienen lugar, as\u00ed como en los factores sociales y culturales que condicionan las capacidades educativas.<\/p>\n<p>Tambi\u00e9n puede participar en el dise\u00f1o de planes de intervenci\u00f3n comunitaria en el \u00e1mbito territorial, promoviendo criterios metodol\u00f3gicos, procesos de implantaci\u00f3n, sistemas de evaluaci\u00f3n etc.<\/p>\n<p>El\/la psic\u00f3logo\/a puede asesorar t\u00e9cnicamente a los responsables de la toma de decisiones de planificaci\u00f3n y actuaci\u00f3n a partir de su pronunciamiento especializado y de su aplicaci\u00f3n al an\u00e1lisis y estudio del sistema educativo en una l\u00ednea de mejora de la atenci\u00f3n educativa.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"7-_Investigacion_y_docencia\"><\/span>7- Investigaci\u00f3n y docencia:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La investigaci\u00f3n incluye las actividades para el an\u00e1lisis y reflexi\u00f3n sobre el propio trabajo; la mejora y actualizaci\u00f3n de su competencia t\u00e9cnica, la profundizaci\u00f3n y extensi\u00f3n de la teor\u00eda y los procedimientos propios de la psicolog\u00eda de la educaci\u00f3n.<\/p>\n<p>La docencia que realizan los profesionales de la psicolog\u00eda educativa est\u00e1 orientada a difundir su conocimiento entre los dem\u00e1s profesionales de la educaci\u00f3n, los grupos sociales implicados en esta, los propios psic\u00f3logos y estudiantes de psicolog\u00eda y otros colectivos profesionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una completa gu\u00eda sobre la psicolog\u00eda educativa o educacional: Qu\u00e9 es, cual es su objetivo, los or\u00edgenes, autores y teor\u00edas influyentes, \u00e1reas de aplicaci\u00f3n. Descubre [&#8230;]<\/p>\n","protected":false},"author":116,"featured_media":25737,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1283,1509],"tags":[2699,1696,2525],"class_list":["post-25481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ninos","category-salud-del-cerebro","tag-aprender-a-educar","tag-cerebro","tag-psicologia"],"_links":{"self":[{"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/posts\/25481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/users\/116"}],"replies":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/comments?post=25481"}],"version-history":[{"count":0,"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/posts\/25481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/media\/25737"}],"wp:attachment":[{"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/media?parent=25481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/categories?post=25481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yourbrain.health\/es\/wp-json\/wp\/v2\/tags?post=25481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}