{"id":15273,"date":"2017-05-08T07:49:08","date_gmt":"2017-05-08T07:49:08","guid":{"rendered":"https:\/\/healthbrain.wpengine.com\/?p=15273\/"},"modified":"2017-10-02T10:36:08","modified_gmt":"2017-10-02T10:36:08","slug":"prokrastination-ueberwinden-20-tipps","status":"publish","type":"post","link":"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/","title":{"rendered":"Prokrastination. Schiebst du alles auf? 20 hilfreiche Tipps f\u00fcr&#8217;s Prokrastinieren"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<blockquote>\n<p style=\"text-align: center;\"><em>H\u00f6rst du nicht auf, ein wichtiges Projekt aufzuschieben oder eine wichtige Aufgabe zu vertagen? In diesem Artikel wird erkl\u00e4rt, was es bedeutet zu prokrastinieren, welche Gr\u00fcnde und Folgen es hat und welche Vor- und Nachteile dieses Verhalten bietet. Au\u00dferdem haben wir 20 wertvolle Tipps, die helfen, die Prokrastination zu \u00fcberwinden.<\/em><\/p>\n<\/blockquote>\n<div id=\"attachment_14449\" style=\"width: 870px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14449\" class=\"Prokrastination wp-image-14449 size-large\" title=\"Prokrastination\" src=\"https:\/\/healthbrain.wpengine.com\/wp-content\/uploads\/2017\/03\/Procastinar-1024x683.jpg\" alt=\"Prokrastination\" width=\"860\" height=\"574\" srcset=\"https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar-1024x683.jpg 1024w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar-300x200.jpg 300w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar-768x512.jpg 768w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar-640x427.jpg 640w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar-150x100.jpg 150w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar.jpg 2048w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><p id=\"caption-attachment-14449\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Prokrastination<\/span><\/p><\/div>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04c11d721a6\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04c11d721a6\" checked aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#Prokrastination_ueberwinden_Was_bedeutet_Prokrastinieren\" >Prokrastination \u00fcberwinden: Was bedeutet Prokrastinieren?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#Prokrastination_ueberwinden_Gruende_fuer_Prokrastination\" >Prokrastination \u00fcberwinden: Gr\u00fcnde f\u00fcr Prokrastination<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#Prokrastination_ueberwinden_Folgen_der_Prokrastination\" >Prokrastination \u00fcberwinden: Folgen der Prokrastination<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#Prokrastination_im_Unternehmen\" >Prokrastination im Unternehmen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#Prokrastination_in_der_Schule\" >Prokrastination in der Schule<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#Prokrastination_ueberwinden_20_Tipps\" >Prokrastination \u00fcberwinden: 20 Tipps<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#1_Mach_dir_klar_dass_es_ohne_Anstrengung_nicht_klappt\" >1. Mach dir klar, dass es ohne Anstrengung nicht klappt<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#2_Notiere_deine_Prioritaeten\" >2. Notiere deine Priorit\u00e4ten<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#3_Sei_realistisch\" >3. Sei realistisch<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#4_Erinnere_dich_daran_was_dich_motiviert\" >4. Erinnere dich daran, was dich motiviert<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#5_Hab_kein_Angst_beim_Versuch_zu_scheitern\" >5. Hab kein Angst beim Versuch zu scheitern<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#6_Plane_deine_Aufgaben\" >6. Plane deine Aufgaben<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#7_Setze_dir_einen_Zeitrahmen\" >7. Setze dir einen Zeitrahmen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#8_Reflektiere_deine_Taten_und_Emotionen\" >8. Reflektiere deine Taten und Emotionen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#9_Belohne_dich_fuer_gut_gemachte_Arbeit\" >9. Belohne dich f\u00fcr gut gemachte Arbeit<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#10_Versuche_Spass_an_der_Arbeit_zu_haben\" >10. Versuche Spa\u00df an der Arbeit zu haben<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#11_Mache_richtige_Pausen\" >11. Mache richtige Pausen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#12_Erhole_dich_von_Zeit_zu_Zeit\" >12. Erhole dich von Zeit zu Zeit<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#13_Lege_Essenszeiten_fest\" >13. Lege Essenszeiten fest<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#14_Ordne_deinen_Arbeitsplatz\" >14. Ordne deinen Arbeitsplatz<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#15_Entferne_Ablenkungsmoeglichkeiten_aus_deinem_Sichtfeld\" >15. Entferne Ablenkungsm\u00f6glichkeiten aus deinem Sichtfeld<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#16_Lenke_dich_nicht_dadurch_ab_dass_du_mit_Leuten_sprichst\" >16. Lenke dich nicht dadurch ab, dass du mit Leuten sprichst<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#17_Schalte_dein_Handy_auf_lautlos\" >17. Schalte dein Handy auf lautlos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#18_Finde_deine_eigene_Methode\" >18. Finde deine eigene Methode<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#19_Bestrafe_dich_nicht_zu_sehr_fuers_Prokrastinieren\" >19. Bestrafe dich nicht zu sehr f\u00fcrs Prokrastinieren<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#20_Konsultiere_einen_Spezialisten_wenn_du_Hilfe_brauchst\" >20. Konsultiere einen Spezialisten, wenn du Hilfe brauchst<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/yourbrain.health\/de\/prokrastination-ueberwinden-20-tipps\/#Prokrastination_ueberwinden_Vorteile_und_Nachteile_der_Prokrastination\" >Prokrastination \u00fcberwinden: Vorteile und Nachteile der Prokrastination<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Prokrastination_ueberwinden_Was_bedeutet_Prokrastinieren\"><\/span>Prokrastination \u00fcberwinden: Was bedeutet Prokrastinieren?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>Prokrastination stammt aus dem Latein <\/strong>und bedeutet so viel wie <strong>&#8220;vertagen&#8221; oder &#8220;aufschieben&#8221;<\/strong>. Wen f\u00fchrt es nicht in Versuchung die unangenehmen Aufgaben vor sich herzuschieben? Dabei ist es egal, ob wir eine E-Mail beantworten m\u00fcssen, die Garage aufger\u00e4umt werden sollte, ein Missverst\u00e4ndnis gekl\u00e4rt oder eine andere Aufgabe erledigt werden muss. Immer gibt es irgendetwas, das uns ablenkt. Uns f\u00e4llt ein, dass wir die Gl\u00fchbirne wechseln wollten, dass noch ein leckeres St\u00fcck Kuchen im K\u00fchlschrank wartet oder unsere Freunde im Gruppenchat lustige Bildchen geschickt haben, die wir uns unbedingt angucken wollen.<\/p>\n<p>Diese Situationen kommen wahrscheinlich jedem von uns bekannt vor (gut m\u00f6glich, dass du gerade in diesem Moment auch dabei bist zu prokrastinieren&#8230;?). Die Mehrheit von uns w\u00fcnscht sich im Nachhinein, die Aufgabe ohne Prokrastination erledigt zu haben, um in der Nacht vor der Abgabe ruhigen Gewissens schlafen zu k\u00f6nnen. Im Folgenden erf\u00e4hrst du, was du gegen dieses Ph\u00e4nomen unternehmen kannst und was du tun kannst, damit Prokrastination deiner Vergangenheit angeh\u00f6rt.<\/p>\n<blockquote><p><strong>&#8220;Was du heute kannst besorgen, das verschiebe nicht auf morgen.&#8221;<\/strong><\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"Prokrastination_ueberwinden_Gruende_fuer_Prokrastination\"><\/span>Prokrastination \u00fcberwinden: Gr\u00fcnde f\u00fcr Prokrastination<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Gr\u00fcnde weshalb wir einen Teil unseres Lebens damit verbringen Aufgaben vor uns herzuschieben sind zahlreich und liegt in der Natur des Menschen. Obwohl niemand ohne Unterbrechungen den ganzen Tag arbeiten kann, gibt es gro\u00dfe Unterschiede darin, wie viel Zeit wir damit verbringen zu prokrastinieren. <strong>Es gibt Leute die hierf\u00fcr anf\u00e4lliger sind als andere.<\/strong> Bei einigen ist es eine Angewohnheit in kurzen Momenten etwas anderes zutun (diese Leute prokrastinieren nicht wirklich), f\u00fcr andere wiederum\u00a0entstehen dadurch ernst zunehmende Probleme und die Arbeit wird \u00fcber Stunden hinausz\u00f6gert.<\/p>\n<p>Die Gr\u00fcnde, die uns in die Prokrastination treiben sind vielz\u00e4hlig. Einige die dazu beitragen sind Langeweile, <a href=\"https:\/\/www.cognifit.com\/brain\/konzentration\" target=\"_blank\" rel=\"noopener\">Konzentration<\/a>sprobleme, Ersch\u00f6pfung, Konzentrationsmangel, Angst vor Versagen, etc.<\/p>\n<p>Kennst du jemanden, der\u00a0<em>noch nie<\/em> prokrastiniert hat? In unserem Leben m\u00fcssen wir unz\u00e4hlige Aufgaben erledigen auf die wir keine Lust haben, die uns wom\u00f6glich sogar sehr unangenehm sind. Da erscheint es nat\u00fcrlich viel verlockender die Fliesen auf dem Boden zu betrachten oder lustige Katzenvideos im Internet anzugucken. Manchmal motivieren wir uns sogar, eine andere Aufgabe anzufangen, verschieben sie dann aber doch, weil wir nicht wissen, wie wir sie beginnen sollen oder weil wir Angst haben uns mit dem Ergebnis selbst zu entt\u00e4uschen.<\/p>\n<p>Obwohl wir eigentlich wissen, dass es besser ist sich Aufgabe in kleine Teilaufgaben zu unterteilen und Arbeit Ruhe und Zeit ben\u00f6tigt, scheinen wir das alles zu vergessen, sobald\u00a0wir die unz\u00e4hligen Ablenkungsm\u00f6glichkeiten vor uns finden. Sei es der Computer, das Handy oder sogar ein wei\u00dfes Blatt Papier.<\/p>\n<p>Durch die neuen Technologien wie Smartphone und Laptop ist die Anzahl der M\u00f6glichkeiten uns von den eigentlichen Aufgaben abzulenken ins Unermessliche gestiegen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h2><span class=\"ez-toc-section\" id=\"Prokrastination_ueberwinden_Folgen_der_Prokrastination\"><\/span>Prokrastination \u00fcberwinden: Folgen der Prokrastination<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Schuldgef\u00fchle:<\/strong>\u00a0Sehr h\u00e4ufig kommt es zu Gedanken wie &#8220;Ich h\u00e4tte nicht so viel Zeit verlieren sollen&#8221;.<\/li>\n<li><strong>Stress:<\/strong>\u00a0Nachdem wir den Berg an Aufgaben betrachten, der sich nach einer Woche Prokrastination angesammelt hat, treten die Anzeichen und Symptome von Stress auf und erinnern uns daran, dass wir endlich\u00a0ernsthaft anfangen m\u00fcssen zu arbeiten. (<a href=\"https:\/\/healthbrain.wpengine.com\/de\/stressbewaeltigung-techniken-tipps\/\" target=\"_blank\" rel=\"noopener\">So bew\u00e4ltigt man Stress<\/a>)<\/li>\n<li><strong>Geringere Leistung:<\/strong>\u00a0Ganz offensichtlich kommt es zu Leistungseinbu\u00dfen, wenn wir zu viel Zeit damit verbringen lustige Videos im Internet anzugucken, oder anfangen unsere Kassenbons zu sortieren. Es bleibt uns dann nur noch ein kostbarer Moment, um die eigentliche Aufgabe zu erledigen, was dazu f\u00fchrt, dass unsere <a href=\"https:\/\/www.cognifit.com\/de\/aufmerksamkeit\" target=\"_blank\" rel=\"noopener\">Aufmerksamkeit<\/a> und <a href=\"https:\/\/healthbrain.wpengine.com\/de\/wichtigkeit-der-motivation\/\" target=\"_blank\" rel=\"noopener\">Motivation<\/a> schwindet.<\/li>\n<li><strong>Vorw\u00fcrfe von Arbeitskollegen oder Vorgesetzten:<\/strong>\u00a0\u00dcblicherweise sind Leute, die prokrastinieren am Arbeitsplatz nicht beliebt, vor allem wenn sich das negativ auf ihre Leistung auswirkt. Das f\u00fchrt in der Regel zu Kritik und Antipathie. Im Extremfall kann Prokrastination sogar dazu f\u00fchren, dass wir unseren Arbeitsplatz verlieren.<\/li>\n<li><strong>Schamgef\u00fchl:<\/strong>\u00a0Wenn uns andere Leute verurteilen, l\u00f6st das in der Regel ein Schamgef\u00fchl bei uns aus. Diese negative Selbstbewertung und das Bed\u00fcrfnis uns zu verstecken, kann dazu f\u00fchren, dass wir unsere Aufgaben unterbrechen. Au\u00dferdem kann es ernstzunehmende Folgen f\u00fcr unsere mentale Gesundheit haben.<\/li>\n<li><strong>Prokrastinationsspirale: <\/strong>Wenn wir aufgrund mangelnder Anstrengung keine positive R\u00fcckmeldung auf der Arbeit erhalten, kann das zur Folge haben, dass wir noch mehr der Gewohnheit verfallen zu prokrastinieren. Das kann zu einer Spirale voller Selbstvorw\u00fcrfe, Selbsthass, einem geringen Selbstwertgef\u00fchl und \u00a0Selbstwirksamkeit f\u00fchren.<\/li>\n<\/ul>\n<p><strong>Prokrastination ist in vielen Bereichen des Lebens pr\u00e4sent.<\/strong>\u00a0Selbst im Alltag kann es sein, dass wir Aufgaben vor uns herschieben, die langfristig eigentlich unser Wohlbefinden verbessern w\u00fcrden, wie Beziehungsprobleme anzusprechen oder uns im Fitnessstudio anzumelden. Im Folgenden werden zwei grundlegende Bereiche vorgestellt, in denen es zu Prokrastination kommt..<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Prokrastination_im_Unternehmen\"><\/span>Prokrastination im Unternehmen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Die Gewohnheit der Prokrastination in Unternehmen ist ein gro\u00dfes Problem f\u00fcr jegliche Art von Organisation.<\/strong>\u00a0\u00dcber die E-Mail-Adresse der Arbeit pers\u00f6nliche Nachrichten zu schreiben, w\u00e4hrend der Arbeitszeit mit der Familie zu telefonieren oder uns anderen arbeitsfernen Dingen zu widmen sind Gewohnheiten die den Arbeitsablauf verz\u00f6gern. Das Unternehmen kann hierbei Geld verlieren und wir verpassen vielleicht die Chance einer Bef\u00f6rderung, oder werden sogar f\u00fcr dieses Verhalten bestraft. Offensichtlich ist es kein Problem, wenn wir in einem bestimmten Rahmen andere Dinge erledigen, aber wenn wir diese nicht unter Kontrolle haben, so kann dies schnell zur Routine werden, die anschlie\u00dfen schwierig zu durchbrechen ist.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h3><span class=\"ez-toc-section\" id=\"Prokrastination_in_der_Schule\"><\/span>Prokrastination in der Schule<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Welche Auswirkungen hat die Prokrastination auf die schulische Leistung? In der Schule oder Universit\u00e4t zu prokrastinieren ist sehr \u00fcblich. Oft ist es so, dass wir das was wir lernen sollen langweilig finden oder es uns schwer f\u00e4llt den Inhalt zu verstehen. Nicht selten kommt es vor, dass wir von anderen h\u00f6ren &#8220;Ich habe nur letzte Nacht f\u00fcr die Pr\u00fcfung gelernt&#8221;. Wenn wir so vorgehen, vergessen wir das Gelernt in der Regel sehr schnell.<\/p>\n<p>Manchmal geht diese Strategie auf, dass wir 24 Stunden fast ohne zu Schlafen da sitzen und uns das Wissen in den Kopf pressen, indem wir ohne Pausen zu machen schreiben, markieren und lesen. Selten f\u00fchrt das Ganze jedoch zu wirklich guten Ergebnissen und vor allem kommt es nicht zu einem signifikanten Lernerfolg.<\/p>\n<p><a href=\"https:\/\/healthbrain.wpengine.com\/de\/schneller-lernen-strategien\/\" target=\"_blank\" rel=\"noopener\">Gute Lernstrategien<\/a> sind ein Schl\u00fcssel zum Erfolg f\u00fcr alle Studierenden. Die Prokrastination im akademischen Bereich kann dazu f\u00fchren, dass die Aufgabenausf\u00fchrung behindert wird, was oft zur Folge hat, dass die betroffene Person davon ausgeht, dass &#8220;studieren nichts f\u00fcr sie\u00a0sei&#8221;. Das f\u00fchrt oft zu negativen Gef\u00fchlen, welche die Motivation zu Lernen ausbremsen.<\/p>\n<p>In diesem Video erkl\u00e4rt der Blogger Tim Urban auf lustige Art und Weise welche Ursachen und Folgen die Prokrastination hat.<\/p>\n<p><iframe loading=\"lazy\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/arj7oStGLkU?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Prokrastination_ueberwinden_20_Tipps\"><\/span>Prokrastination \u00fcberwinden: 20 Tipps<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Uns beeindrucken die Leute, die ihre Aufgaben z\u00fcgig und deutlich vor Ablauf der Frist abgeben und gleichzeitig nebenbei noch ins Fitnessstudio gehen, Musikunterricht nehmen und Zeit haben ihre Freunde zu sehen. Wie erreichen sie diesen Grad an Organisiertheit? Sind sie besser als wir?<\/p>\n<p>Dadurch, dass es sehr unwahrscheinlich ist, dass diese Leute \u00fcber Superkr\u00e4fte verf\u00fcgen, ist es wohl eher so, dass diese Leute es schaffen dem Impuls zu prokrastinieren Stand zu halten und so Zeit f\u00fcr die wichtigen Dinge im Leben zu finden. Du kannst es ebenfalls schaffen\u00a0die Prokrastination zu \u00fcberwinden! Im Folgenden werden dir einige Vorschl\u00e4ge und Tipps gegeben, um unn\u00f6tige Ablenkung zu vermeiden.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"1_Mach_dir_klar_dass_es_ohne_Anstrengung_nicht_klappt\"><\/span>1. Mach dir klar, dass es ohne Anstrengung nicht klappt<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es existiert kein Geheimnis, das uns auf einmal erlaubt alle Aufgaben in der H\u00e4lfte der Zeit ohne Ablenkung zu erledigen und\u00a0dabei nicht zu prokrastinieren. Ebenso wenig werden wir dabei auf einmal wahnsinnig Spa\u00df haben, ohne daf\u00fcr einen Aufwand betreiben zu m\u00fcssen. Was wir aber tun k\u00f6nnen, ist unsere Einstellung unseren Aufgaben gegen\u00fcber zu ver\u00e4ndern und ihnen anders zu begegnen.<\/p>\n<p>Vielleicht schaffen wir es dadurch am Ende sogar unsere Aufgaben nicht als Pflicht wahrzunehmen, sondern als machbare Herausforderung anzusehen, was uns ein Gef\u00fchl von Kompetenz bei der Ausf\u00fchrung gibt.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2_Notiere_deine_Prioritaeten\"><\/span>2. Notiere deine Priorit\u00e4ten<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Wenn wir gleichzeitig daran denken, dass wir ein Haustier wollen, die W\u00e4sche waschen m\u00fcssen, bis morgen 20 Seiten schreiben sollen und Kaugummis kaufen werden, usw&#8230;. ist es gut m\u00f6glich, dass uns die Vielfalt an Vorhaben erdr\u00fcckt und wir nicht wissen, wo wir anfangen sollen. Wenn wir jedoch eine Hierarchie bilden (und uns anschlie\u00dfend an den Ablauf halten) haben wir den Eindruck, dass es viel leichter ist unsere Vorhaben in die Tat umzusetzen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h3><span class=\"ez-toc-section\" id=\"3_Sei_realistisch\"><\/span>3. Sei realistisch<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es ist sehr unwahrscheinlich, dass du zwei Wochen nach China gehst und anschlie\u00dfend die Sprache flie\u00dfend beherrscht. Ebenso wenig schaffen wir es das beste Projekt zu entwerfen, wenn wir die Vorgaben nicht verstanden haben. Es ist genauso wichtig zu wissen was wir wollen, wie uns realistische Ziele zu setzen. Au\u00dferdem kann es von Vorteil sein Teile der Aufgaben an andere abzugeben und dadurch auf realistischere Art zum Ziel zu gelangen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"4_Erinnere_dich_daran_was_dich_motiviert\"><\/span>4. Erinnere dich daran, was dich motiviert<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es ist wichtig, dass wir wissen was wir erreichen m\u00f6chten. Dabei gen\u00fcgt es nicht eine vage oder widerspr\u00fcchliche Idee zu haben, ob wir unsere Hausarbeit fertigstellen wollen oder lieber eine Webseite erstellen. Es ist wichtig uns selbst den Weg zu weisen, um nicht vom eigentlichen Ziel abzukommen. Dabei kann es hilfreich sein sich Notizzettel in Sichtweite des Schreibtisches aufzuh\u00e4ngen. Wichtig ist, dass das Ziel keine Traumvorstellung bleibt.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"5_Hab_kein_Angst_beim_Versuch_zu_scheitern\"><\/span>5. Hab kein Angst beim Versuch zu scheitern<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Besiege die Angst vor dem Versagen. Oft erreichen wir unsere Ziele nach dem &#8220;Trial and Error&#8221; Prinzip. Beim Probleml\u00f6sen ist es wichtig verschiedene Dinge auszuprobieren, um die beste L\u00f6sung zu finden. Wenn wir scheitern,k\u00f6nnen wir kreative Ideen finden und den Impuls versp\u00fcren, das Beste geben zu wollen.<\/p>\n<p>Wenn du andererseits wirklich nicht f\u00fcr eine bestimmte Aufgabe vorbereitet bist oder die Aufgabe dich ungl\u00fccklich macht, hab keine Angst die Aufgabe sein zu lassen. Wichtig ist, dass du diese Entscheidung weise und in Ruhe triffst und nicht aus Frustration oder Angst.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"6_Plane_deine_Aufgaben\"><\/span>6. Plane deine Aufgaben<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es reicht nicht die Aufgabe zu planen, denn das kann eine weitere Form von Prokrastination sein, wenn wir nur vage dar\u00fcber nachdenken was und wie wir es tun k\u00f6nnten und schlussendlich nicht so handeln. Es ist wichtig einige Aufgaben vorab zu konkretisieren, nachdem wir entschieden haben: &#8220;Welches sind die relevantesten?&#8221;, &#8220;Wie schwierig sind die Aufgaben ungef\u00e4hr?&#8221;, &#8220;Wie lange werden wir f\u00fcr sie brauchen?&#8221;, usw. Es ist dementsprechend empfehlenswert unsere Arbeit in kleine Schritte zu unterteilen, um die vorangegangenen Fragen besser beantworten zu k\u00f6nnen. Durch diese \u00dcberlegungen k\u00f6nnen wir unsere Arbeit in kleine Schritte unterteilen.<\/p>\n<p>Wenn dein Vorhaben beispielsweise ist, den F\u00fchrerschein zu machen, reicht es nicht zu denken &#8220;eines Tages bestehe ich die Pr\u00fcfung&#8221; oder &#8220;wie sehr ich mich darauf freue mit meinem eigenen Auto in den Urlaub zu fahren&#8221;. Um aufzuh\u00f6ren zu prokrastinieren musst du dich in der Fahrschule anmelden, die Theoriestunden absolvieren, dich auf die Pr\u00fcfung vorbereiten, usw. Setze dir kleine Ziele, die dich Schritt f\u00fcr Schritt leiten.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 5\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h3><span class=\"ez-toc-section\" id=\"7_Setze_dir_einen_Zeitrahmen\"><\/span>7. Setze dir einen Zeitrahmen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Das ist eine schwierige Aufgabe f\u00fcr Leute die professionell prokrastinieren. Aber wir k\u00f6nnen versuchen uns mit kleinen Tricks zu \u00fcberlisten, indem wir beispielsweise das Abgabedatum im Kalender vorr\u00fccken. Wenn wir davon ausgehen, dass wir eine Aufgabe schon am Montag abgeben m\u00fcssen, haben wir vor Ende der echten Deadline mehr Zeit Fehler zu korrigieren.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"8_Reflektiere_deine_Taten_und_Emotionen\"><\/span>8. Reflektiere deine Taten und Emotionen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Wenn du am Ende eines Tages kurz Inne h\u00e4ltst und bewertest, was du schon geschafft hast und was du noch erledigen musst, hast du eine ad\u00e4quatere Vorstellung davon, was am n\u00e4chsten Tag auf dich zukommen wird und wie du dich verbessern kannst. Wenn du au\u00dferdem \u00fcber deine Emotionen nachdenkst, kann dir das helfen diese besser zu steuern und deine Selbstkontrolle zu steigern.<\/p>\n<p>Es kommt h\u00e4ufig vor, dass wir einer Person begegnen, die prokrastiniert, die nicht wei\u00df bis zu welchem Punkt sie ihre Aufgaben eigentlich hinausz\u00f6gert, was wiederum zur Aufrechterhaltung dieses Verhaltens f\u00fchrt. Es raubt uns kaum Zeit kurz zu rekapitulieren welches unsere Fortschritte sind, was au\u00dferdem dazu f\u00fchrt, dass wir unser Ziel noch pr\u00e4ziser erreichen k\u00f6nnen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"9_Belohne_dich_fuer_gut_gemachte_Arbeit\"><\/span>9. Belohne dich f\u00fcr gut gemachte Arbeit<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nach der eigenen Bewertung des Fortschritts gibt es bestimmt Dinge die uns mit Stolz erf\u00fcllen. Wir k\u00f6nnen uns f\u00fcr unsere erreichten Ziele auf verschiedene Art und Weise belohnen: Ein Eis oder Konzertkarten k\u00f6nnen unsere Laune heben und uns motivieren weiter hart zu arbeiten. Indem wir Bewusstsein \u00fcber unsere geleistete Arbeit schaffen, steigern wir unser Selbstbewusstsein und unsere Selbstwirksamkeit.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"10_Versuche_Spass_an_der_Arbeit_zu_haben\"><\/span>10. Versuche Spa\u00df an der Arbeit zu haben<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nicht immer finden wir unseren Traumjob, ebenso wenig k\u00f6nnen uns alle F\u00e4cher Spa\u00df machen, die wir in der Schule besuchen. Nichtsdestotrotz kann ein angenehmes Arbeitsklima und die Auflistung der Vorteile des Arbeitsplatzes dazu beitragen, dass wir aufh\u00f6ren zu prokrastinieren und uns dazu motivieren unsere Aufgaben zu erf\u00fcllen. Wenn man damit erstmal angefangen hat, ist es meistens gar nicht so schwierig und l\u00e4uft vielleicht sogar besser als erwartet.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"11_Mache_richtige_Pausen\"><\/span>11. Mache richtige Pausen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Zu versuchen unsere Arbeit zu machen wenn wir ersch\u00f6pft sind ist kontraproduktiv und f\u00fchrt dazu, dass wir noch mehr prokrastinieren. Es ist wichtig ausreichend zu schlafen und dabei einen geregelten Rhythmus einzuhalten. Ein erholsamer Schlaf f\u00fchrt au\u00dferdem zu einer besseren Ged\u00e4chtnisleistung.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"12_Erhole_dich_von_Zeit_zu_Zeit\"><\/span>12. Erhole dich von Zeit zu Zeit<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Selbst wenn wir nur noch wenig Zeit haben um eine Aufgabe zu beenden, ist es wichtig, dass wir uns die Zeit nehmen einen Schritt zur\u00fcck zu treten um anschlie\u00dfend Fehler besser entdecken zu k\u00f6nnen, oder neue Perspektiven zu erlangen. Andererseits ist es wichtig eine maximale Pausenzeit zu definieren. Wenn wir nicht kontrollieren wie h\u00e4ufig und wie lange wir pausieren, f\u00fchrt das in der Regel nur dazu, dass wir weiterhin prokrastinieren.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 6\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h3><span class=\"ez-toc-section\" id=\"13_Lege_Essenszeiten_fest\"><\/span>13. Lege Essenszeiten fest<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Unser Dienst- oder Stundenplan l\u00e4sst manchmal wenig Spielraum unsere Essenszeiten einzuhalten. Um die Prokrastination zu \u00fcberwinden ist es aber wichtig Essenszeiten festzulegen, damit wir dem K\u00fchlschrank nicht mehr Besuche abstatten als notwendig.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"14_Ordne_deinen_Arbeitsplatz\"><\/span>14. Ordne deinen Arbeitsplatz<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Wenn sich auf unserem Schreibtisch der Schl\u00fcsselbund, die Postkarte unserer Freunde, Notizen von vor drei Jahren, die neuen Str\u00fcmpfe und ein paar Stifte in kompletter Unordnung befinden ist es sehr wahrscheinlich, dass wir die entscheidenden Objekte nicht griffbereit haben oder uns am Anblick an diesem Chaos st\u00f6ren und dadurch ablenken lassen.<\/p>\n<p>Sich anzugew\u00f6hnen Dinge nach der Benutzung wieder an einen bestimmten Ort zu legen, kann schwierig erscheinen. Doch auch wer diese Gewohnheit bisher nicht pflegt, sollte damit beginnen. Dies bedarf einer gewissen Anpassungszeit, offensichtlich lassen sich Gewohnheiten nicht an einem Tag \u00e4ndern. Um uns das Prokrastinieren abzugew\u00f6hnen sollten wir jedoch versuchen unseren Arbeitsplatz ein wenig zu entr\u00fcmpeln.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"15_Entferne_Ablenkungsmoeglichkeiten_aus_deinem_Sichtfeld\"><\/span>15. Entferne Ablenkungsm\u00f6glichkeiten aus deinem Sichtfeld<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Mit einem aufger\u00e4umten und angenehmen Arbeitsumfeld ist es noch nicht getan. Es ist auch wichtig zu wissen, welche Dinge uns davon abhalten zu arbeiten. M\u00fcssen wir wirklich all diese Tabs in unserem Browser ge\u00f6ffnet haben? Und dieses Spiel hier stehen zu haben was uns geschenkt wurde? Sehr wahrscheinlich nicht. Dinge aus dem Sichtfeld zu schaffen kann nicht verhindern, dass wir anfangen uns mit ihnen abzulenken, verringert aber die Wahrscheinlichkeit.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"16_Lenke_dich_nicht_dadurch_ab_dass_du_mit_Leuten_sprichst\"><\/span>16. Lenke dich nicht dadurch ab, dass du mit Leuten sprichst<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Unsere sozialen Kontakte zu pflegen ist wichtig f\u00fcr eine gute Leistungsf\u00e4higkeit. Gleichzeitig ist es aber elementar, dass wir uns konzentrieren,wenn wir m\u00fcssen. Bei Gruppenarbeiten ist es sinnvoll ein paar Grundregeln aufzustellen und uns bewusst dar\u00fcber zu sein welches die gemeinsamen Ziele sind.<\/p>\n<p>\u00dcbrigens ist soziale Unterst\u00fctzung fundamental um Ziele zu erreichen. Unsere Freunde, Familie und Partner werden Verst\u00e4ndnis daf\u00fcr haben, dass wir ein Ziel verfolgen und im Anschluss an die Arbeit sprechen k\u00f6nnen, ohne uns schlecht zu f\u00fchlen dass wir prokrastinieren. Wenn wir unsere Ziele mit anderen Leuten teilen, werden sie uns selbst bewusster, was unser eigenes Pflichtbewusstsein sch\u00e4rft.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 7\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h3><span class=\"ez-toc-section\" id=\"17_Schalte_dein_Handy_auf_lautlos\"><\/span>17. Schalte dein Handy auf lautlos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Das Handy ist eines der h\u00e4ufigsten Ablenkungsquellen und sollte deswegen gesondert in Betracht gezogen werden. Wenn wir einen wichtigen Anruf erwarten, erscheint uns dies unm\u00f6glich, in den meisten F\u00e4llen lenken uns aber Nachrichten von Freunden ab, die uns erz\u00e4hlen was sie gestern Abend unternommen haben oder wir erhalten Nachrichten von sozialen Netzwerken. Um Ablenkung zu vermeiden kann es helfen das Handy lautlos zu schalten, den Flugmodus zu aktivieren, wenn wir besch\u00e4ftigt sind.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"18_Finde_deine_eigene_Methode\"><\/span>18. Finde deine eigene Methode<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Von den genannten Techniken kannst du alle m\u00f6glichen Kombinationen ausprobieren und die sein lassen, die nicht funktionieren. Jeder muss dabei seine eigenen kleinen Tricks herausfinden. Mach dir bewusst welche Strategien dir helfen deine Ziele zu erreichen und das Prokrastinieren zu unterlassen\u00a0und welche nicht.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"19_Bestrafe_dich_nicht_zu_sehr_fuers_Prokrastinieren\"><\/span>19. Bestrafe dich nicht zu sehr f\u00fcrs Prokrastinieren<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Vielleicht versuchst du seit Monaten deine Bachelorarbeit zu schreiben, einen Job zu suchen oder\u00a0du schiebst irgendeine andere Aufgabe vor dir her. Wir wir mittlerweile wissen kann das schwerwiegende Konsequenzen f\u00fcr uns und unser Wohlbefinden haben.<\/p>\n<p>Es ist empfehlenswert uns auf die Zukunft zu konzentrieren. Was in der Vergangenheit passiert ist l\u00e4sst sich nicht mehr \u00e4ndern. Wir k\u00f6nnen uns jedoch\u00a0auf neue Ziele und Herausforderungen konzentrieren und unsere Einstellungen ihnen gegen\u00fcber ver\u00e4ndern.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"20_Konsultiere_einen_Spezialisten_wenn_du_Hilfe_brauchst\"><\/span>20. Konsultiere einen Spezialisten, wenn du Hilfe brauchst<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Prokrastination kann die Folge eines anderen psychologischen Problems, wie einer Depression oder Angstst\u00f6rung, sein. Wenn du das Gef\u00fchl hast zu stark zu prokrastinieren und die negativen Konsequenzen dieser Angewohnheit zu sp\u00fcren bekommst, obwohl du wirklich versucht hast dem entgegen zu wirken, ist es empfehlenswert einen Spezialisten aufzusuchen.<\/p>\n<p>Wenn diese Gewohnheit zu einem Hindernis wird unsere pers\u00f6nlichen und Beruflichen Ziele zu verfolgen und uns weiterzuentwickeln, kann uns ein Experte helfen, den Ursachen des Problems auf den Grund zu gehen und das Problem zu l\u00f6sen.<\/p>\n<div id=\"attachment_14457\" style=\"width: 870px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14457\" class=\"wp-image-14457 size-large\" src=\"https:\/\/healthbrain.wpengine.com\/wp-content\/uploads\/2017\/03\/Procastinar_ventajas-1024x683.jpg\" alt=\"Procastinar: \u00bfTiene ventajas?\" width=\"860\" height=\"574\" srcset=\"https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar_ventajas-1024x683.jpg 1024w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar_ventajas-640x427.jpg 640w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar_ventajas-300x200.jpg 300w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar_ventajas-768x512.jpg 768w, https:\/\/yourbrain.health\/wp-content\/uploads\/2017\/03\/Procastinar_ventajas-150x100.jpg 150w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><p id=\"caption-attachment-14457\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Prokrastination: Gibt es Vorteile?<\/span><\/p><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Prokrastination_ueberwinden_Vorteile_und_Nachteile_der_Prokrastination\"><\/span>Prokrastination \u00fcberwinden: Vorteile und Nachteile der Prokrastination<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>In diesem Artikel haben wir uns auf die negativen Folgen der Prokrastination konzentriert. Wir wissen also bereits, dass es zahlreiche negative Konsequenzen hat und wie tiefgreifend sie bestimmte Lebensbereiche beeinflussen k\u00f6nnen. Wir wollen an dieser Stelle aber auch die positiven Seiten dieser Angewohnheit kurz beleuchten. <strong>Es gibt auch Vorteile.<\/strong> Im Folgenden findest du die wichtigsten Vorteile der Prokrastination:<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 8\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<ul>\n<li><strong>Manchmal ist es notwendig Druck zu versp\u00fcren<\/strong>: In Momenten wenn nur noch wenig Zeit bis zur Deadline bleibt, geben wir am meisten und arbeiten oft sehr effektiv.<\/li>\n<li><strong>Prokrastination kann uns Zeit zum Denken geben:<\/strong> Indem wir eine Arbeit unterbrechen, k\u00f6nnen wir uns dar\u00fcber bewusst werden, dass wir nicht den richtigen Weg eingeschlagen haben. Sich von einer Arbeit zu distanzieren ist wichtig um eine objektivere Sicht zu erlangen.<\/li>\n<li><strong>F\u00f6rdert unsere Kreativit\u00e4t:<\/strong>\u00a0Manchmal kann es dazu kommen, dass wir eine Idee f\u00fcr unsere Arbeit bekommen, w\u00e4hrend wir dabei sind unseren Sitznachbarn zu zeichnen.<\/li>\n<li><strong>Erm\u00f6glicht uns Spa\u00df:<\/strong>\u00a0Einen Teil unserer Zeit Dingen zu widmen, die uns Freude bereiten, hilft uns produktiver zu sein. Dabei ist es wichtig nicht zu \u00fcbertreiben und unsere Pflichten nicht zu vergessen.<\/li>\n<\/ul>\n<p><strong>Wichtig ist, dass wir die Prokrastination soweit unter Kontrolle haben, dass sie unser Leben nicht negativ beeinflusst.\u00a0<\/strong><\/p>\n<p>Vielen Dank, dass du diesen Artikel gelesen hast. Falls du eine Frage hast oder uns deine Tipps gegen Prokrastination mitteilen m\u00f6chtest, hinterlasse einen Kommentar!<\/p>\n<\/div>\n<p>\u00dcbersetzt aus dem Spanischen. Original: <a href=\"https:\/\/healthbrain.wpengine.com\/es\/author\/ainhoa-arranz\/\" target=\"_blank\" rel=\"noopener\">Ainhoa Arranz Aldana<\/a>, Psychologin bei CogniFit.<\/p>\n<div class=\"entry-meta postmeta\"><\/div>\n<div class=\"column\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>H\u00f6rst du nicht auf, ein wichtiges Projekt aufzuschieben oder eine wichtige Aufgabe zu vertagen? In diesem Artikel wird erkl\u00e4rt, was es bedeutet zu prokrastinieren, welche [&#8230;]<\/p>\n","protected":false},"author":76,"featured_media":14450,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[4413,5100,6528,6525,6527,1149,6524,6526,9310,260],"class_list":["post-15273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-akademische-leistungsfaehigkeit","tag-arbeitsstress","tag-effektivitaet","tag-leistung","tag-leistung-optimieren","tag-motivation","tag-prokrastination","tag-prokrastination-ueberwinden","tag-stress-de","tag-stress"],"_links":{"self":[{"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/posts\/15273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/comments?post=15273"}],"version-history":[{"count":0,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/posts\/15273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/media\/14450"}],"wp:attachment":[{"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/media?parent=15273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/categories?post=15273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/tags?post=15273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}