{"id":10782,"date":"2016-09-07T13:34:23","date_gmt":"2016-09-07T13:34:23","guid":{"rendered":"https:\/\/healthbrain.wpengine.com\/de\/?p=10782"},"modified":"2019-10-08T10:26:07","modified_gmt":"2019-10-08T10:26:07","slug":"ich-bin-traurig","status":"publish","type":"post","link":"https:\/\/yourbrain.health\/de\/ich-bin-traurig\/","title":{"rendered":"Ich bin traurig &#8211; Was kann ich tun, um die Traurigkeit zu \u00fcberwinden?"},"content":{"rendered":"<p style=\"text-align: center;\"><em>&#8220;Ich kann nicht mehr. Ich hab es satt.&#8221; &#8220;Ich bin traurig. Ich ertrage mein Leben nicht. Ich will mich nicht vom Sofa bewegen.&#8221; &#8220;Warum hat er mich verlassen? Was soll ich ohne ihn machen?&#8221; &#8220;Ich wollte nicht, dass sie geht. Ich realisiere nicht, dass sie gegangen ist.&#8221; &#8220;Ich habe keine Lust auf gar nichts. Ich habe keinen Hunger. Ich m\u00f6chte nichts essen.&#8221; Wenn du einen dieser Gedanken schon einmal gehabt hast oder gerade hast, kann es sein, dass du durch eine vor\u00fcbergehende Trauerphase gehst. Wenn du die Trauer \u00fcberwinden m\u00f6chtest, erz\u00e4hlen wir in diesem Post, wie das geht.<\/em><\/p>\n<div id=\"attachment_10729\" style=\"width: 3149px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10729\" class=\"wp-image-10729 size-full\" title=\"Ich bin traurig\" src=\"https:\/\/healthbrain.wpengine.com\/wp-content\/uploads\/2016\/09\/estoy-triste.jpeg\" alt=\"Ich bin traurig\" width=\"3139\" height=\"2354\" srcset=\"https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/estoy-triste.jpeg 2048w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/estoy-triste-300x225.jpeg 300w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/estoy-triste-768x576.jpeg 768w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/estoy-triste-640x480.jpeg 640w, https:\/\/yourbrain.health\/wp-content\/uploads\/2016\/09\/estoy-triste-1024x768.jpeg 1024w\" sizes=\"auto, (max-width: 3139px) 100vw, 3139px\" \/><p id=\"caption-attachment-10729\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Ich bin traurig<\/span><\/p><\/div>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04bf8d24137\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04bf8d24137\" checked aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/yourbrain.health\/de\/ich-bin-traurig\/#Ich_bin_traurig_%E2%80%93_Was_ist_Trauer\" >Ich bin traurig &#8211; Was ist Trauer?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/yourbrain.health\/de\/ich-bin-traurig\/#Ich_bin_traurig-_Trauer_und_Depression_Wie_unterscheiden_sie_sich\" >Ich bin traurig- Trauer und Depression: Wie unterscheiden sie sich?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/yourbrain.health\/de\/ich-bin-traurig\/#Ich_bin_traurig_%E2%80%93_Wie_ueberwinde_ich_die_Trauer\" >Ich bin traurig &#8211; Wie \u00fcberwinde ich die Trauer?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/yourbrain.health\/de\/ich-bin-traurig\/#Ich_bin_traurig_%E2%80%93_Die_Physiologie_der_Trauer\" >Ich bin traurig &#8211; Die Physiologie der Trauer<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Ich_bin_traurig_%E2%80%93_Was_ist_Trauer\"><\/span>Ich bin traurig &#8211; Was ist Trauer?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die\u00a0<strong>Trauer\u00a0<\/strong>geh\u00f6rt zur Gruppe der 6 Grundemotionen, die alle menschlichen Wesen haben: Angst, Freude, Ekel, \u00dcberraschung, Wut und Trauer. Traurig zu sein zeichnet sich durch Niedergeschlagenheit, Einsamkeits- und Schuldgef\u00fchle, Ersch\u00f6pfung aus &#8230; es ist eine Reaktion auf unangenehme Ereignisse &#8211; ein unangenehmer Moment, eine Entt\u00e4uschung, der Tod von jemandem, eine Trennung, Streit mit einem nahestehenden Menschen, etc.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Ich_bin_traurig-_Trauer_und_Depression_Wie_unterscheiden_sie_sich\"><\/span>Ich bin traurig- Trauer und Depression: Wie unterscheiden sie sich?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es ist wichtig, Trauer nicht mit Depression zu verwechseln, denn die Ursachen und Merkmale sind nicht dieselben. Depressionen k\u00f6nnen aus verschiedenen Gr\u00fcnden entstehen, oder ihren Ursprung in den Genen haben. Im Laufe unseres Lebens sammeln sich Probleme in uns an, die sich sp\u00e4ter in Form von Depressionen \u00e4u\u00dfern k\u00f6nnen, wenn wir eine genetische Veranlagung daf\u00fcr haben. Eine depressive Person f\u00fchlt sich verlassen, verzweifelt und hat keine Freude am Leben w\u00e4hrend einer langen Zeitspanne. Unterdessen f\u00fchlt sich die Person im Trauerzustand traurig, aber dieses Gef\u00fchl ist vor\u00fcbergehend. Oft betrachtet man dies nicht einmal als Emotion, sondern vielmehr eine Art momentane Gef\u00fchlsanwandlung, die nicht lange andauert. Wenn die Trauer beginnt, in das Leben der Person einzudringen, k\u00f6nnte sie sich in Depression verwandeln.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ich_bin_traurig_%E2%80%93_Wie_ueberwinde_ich_die_Trauer\"><\/span><strong>Ich bin traurig &#8211; Wie \u00fcberwinde ich die Trauer?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><em>\u201cIch wache morgens auf. Ich \u00f6ffne die Augen. Was f\u00fcr ein bl\u00f6des Leben. Ich habe keine Lust zu leben. Ich habe keine Lust aufzustehen. Ich kann nicht aufh\u00f6ren an das, was mich bedr\u00fcckt, zu denken. Ich wei\u00df nicht mehr, was ich machen soll. Ich bin traurig.&#8221;<\/em><\/p>\n<ol>\n<li><strong>Die Routine des &#8220;Ja, ich kann!&#8221;<\/strong>\u00a0Wenn dies dein morgendlicher Dialog ist, dann bist du traurig. Du musst deine Einstellung \u00e4ndern! Um die Situation zu ver\u00e4ndern, musst du sie erst einmal akzeptieren. Ja, du bist traurig. Macht nichts. Mach dir keine Sorgen. Einmal akzeptiert, muss man die Traurigkeit \u00fcberwinden. Jeden Morgen musst du daran denken, wie sch\u00f6n es ist zu leben. Daran, wie gro\u00dfe Lust du hast, Sachen zu machen, die dir gefallen und wie wenig es dir dabei helfen wird, im Bett zu bleiben. Wirst du zulassen, dass die Laken dich festhalten? Oder wirst du rausgehen und der Welt zeigen, wer du bist? Du musst zulassen, dass sich diese Gedanken Tag f\u00fcr Tag, nach und nach \u00e4ndern.<\/li>\n<li><strong>Stell dir Herausforderungen.\u00a0<\/strong>Auch wenn du traurig bist, musst du dir jeden Tag beim Aufwachen eine neue Herausforderung stellen. Das kann Laufen gehen sein, Reiten, Wandern, dein Lieblingsessen kochen, Kanufahren, Canyoning oder auch nur den Roman beenden, den du angefangen hast. Aber es ist wichtig, dass du am Ende des Tages sp\u00fcrst, dass du dich selbst verwirklicht hast. Dass du sp\u00fcrst, dass es sich gelohnt hat.<\/li>\n<li><strong>Lass los, was dir wehtut.<\/strong>\u00a0Es ist normal, dass du traurig bist, wenn du eine schwierige Phase durchl\u00e4ufst. Wenn dir gek\u00fcndigt wurde, du dich von deinem Partner getrennt hast, mit jemandem gestritten hast oder ein Familienangeh\u00f6riger nicht mehr da ist, ist es Zeit, ein neues Leben zu beginnen. Wir k\u00f6nnen nicht in vergangenen Geschichten verankert leben. Wir brauchen Action und neue Sichtweisen. Lerne, das Alleinsein zu genie\u00dfen, es ist etwas sehr Sch\u00f6nes und Wichtiges. Es hilft dir dabei, dich kennenzulernen. Es hilft dir dabei, dich lieben zu lernen. Es hilft dir auch dabei, die Traurigkeit zu \u00fcberwinden.<\/li>\n<li><strong>L\u00e4chle, auch wenn du traurig bist.<\/strong>\u00a0Konzentriere dich am Ende des Tages auf die positiven Momente. Denk daran, wie viel du heute gelacht hast und mit wem, an Dinge, die du gemacht hast und die dich richtig gl\u00fccklich gemacht haben, wenn du im Bett liegst. Du musst deine Energie auf die fr\u00f6hlichen Augenblicke lenken und die traurigen vergessen.<\/li>\n<li><strong>Yoga oder Meditation machen.\u00a0<\/strong>Immer mehr Menschen machen bei dieser Art von Aktivit\u00e4ten mit. Sie sind genauso gut f\u00fcr die K\u00f6rperhaltung wie f\u00fcr die Harmonie. Meditieren kann dir dabei helfen, die Trauer zu \u00fcberwinden. Wei\u00dft du nicht, was <a href=\"https:\/\/healthbrain.wpengine.com\/de\/achtsamkeitsmeditation\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mindfulness<\/a> ist? Du kann bei Youtube Tutorials sehen, dich in deinem Viertel f\u00fcr einen Kurs anmelden oder einfach damit beginnen dich mit geschlossenen Augen auf deine Muskeln zu konzentrieren. Du wirst sp\u00fcren dass du dich nach und nach entspannst und sich deine Einstellung \u00e4ndert. Je mehr Fortschritte du in diesen Disziplinen machst, desto entspannter wirst du dich f\u00fchlen.<\/li>\n<li><strong>Besch\u00e4ftige dich an der frischen Luft.<\/strong>\u00a0Auch wenn du traurig bist, du musst rausgehen, um spazieren oder joggen zu gehen, die Landschaft zu fotografieren, das Gras anzufassen, wenn es morgens noch ganz feucht ist, die Baumrinde ber\u00fchren, w\u00e4hrend es d\u00e4mmert, den Fu\u00df ins Meerwasser tauchen, Sandburgen bauen, als w\u00e4rst du ein Kind &#8230; all das sind sehr sinnliche Erfahrungen, die kein Geld kosten. Sie sind in unserer Reichweite und wir nutzen sie nicht. Lass nicht zu, dass dich deine 4 W\u00e4nde festhalten und lauf nach drau\u00dfen.<\/li>\n<li><strong>Adoptiere ein Haustier oder nimm eins auf.\u00a0<\/strong>Es ist wissenschaftlich erwiesen, dass es viele Vorteile hat, ein Haustier zu haben und es dir helfen kann, die Traurigkeit zu \u00fcberwinden. In Tierschutzvereinen kann man Haustiere auf unbestimmte Zeit adoptieren. So sicherst du dir einen Lebenspartner f\u00fcr eine lange Zeit. Nichtsdestotrotz, solltest du dir nicht sicher sein, dass du dich f\u00fcr mehr als eine kurze Zeit um es k\u00fcmmern kannst, nimm eins auf! Das ist eine M\u00f6glichkeit, die immer h\u00e4ufiger genutzt wird. F\u00fcr einige Monate lebt ein Tier bei dir, das Hilfe braucht, und du, der du einen kleinen Schubs zum Gl\u00fcck brauchst, lebst mit ihm zusammen. Daran gewinnt ihr beide.<\/li>\n<li><strong>Sprich mit den Menschen in deiner Umgebung.\u00a0<\/strong>Oft ist es sehr befreiend, uns unsere Probleme von der Seele zu reden. Wir merken, dass sich unsere Last verringert. Wir erleichtern uns. Dieser Trick ist auch sehr gut um unsere Laune zu heben. Wenn du die Gelegenheit hast mit jemandem zu sprechen, der dich versteht, dir Tipps geben kann und bei dem du wei\u00dft, dass er\/sie dir gut tun wird, dann los. Hab keine Angst dich schwach zu zeigen. Wir sind alle manchmal traurig, und wenn wir uns aussprechen m\u00fcssen &#8211; wer ist da besser als ein alter Freund?<\/li>\n<li><strong>Senke die Traurigkeitssymptome mit dem <\/strong><strong><a href=\"https:\/\/www.cognifit.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">personalisierten Hirntraining von CogniFit<\/a><\/strong>: Die Menschen, die Trauer oder Depression versp\u00fcren, leiden unser St\u00f6rungen bei Funktionen wie dem <a href=\"https:\/\/www.cognifit.com\/de\/wissenschaft\/kognitive-fahigkeiten\/arbeitsgedachtnis\" target=\"_blank\" rel=\"noopener\">Arbeitsged\u00e4chtnis<\/a>,\u00a0<a href=\"https:\/\/www.cognifit.com\/de\/wissenschaft\/kognitive-fahigkeiten\/inhibition\" target=\"_blank\" rel=\"noopener noreferrer\">der Inhibition<\/a>, <a href=\"https:\/\/www.cognifit.com\/de\/wissenschaft\/kognitive-fahigkeiten\/geteilte-aufmerksamkeit\" target=\"_blank\" rel=\"noopener noreferrer\">der geteilten Aufmerksamkeit<\/a>, und generell der exekutiven Funktionen.\u00a0<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3651957\/?__hstc=262374355.5c793b820e723a4e43bbb8c9574bed15.1470138530597.1473085033385.1473091348688.71&amp;__hssc=262374355.1.1473091348688&amp;__hsfp=3749001670\" target=\"_blank\" rel=\"noopener noreferrer\">Aktuelle Studien<\/a>\u00a0haben gezeigt, dass das personalisierte Gehirntraining von CogniFit es erleichtert\u00a0<a href=\"https:\/\/www.cognifit.com\/de\/depression\" target=\"_blank\" rel=\"noopener noreferrer\">depressive Symptome zu verringern<\/a>, indem es dem Patienten erleichtert, bessere Strategien gegen das Gr\u00fcbeln und die Sturheit (Typische Symptome von Trauer und Depression) zu entwickeln.<\/li>\n<\/ol>\n<p>Zu guter Letzt, wenn du merkst, dass die Traurigkeitsgef\u00fchle anhalten, ist es empfehlenswert einen Spezialisten aufzusuchen. Vielleicht brauchst du die Hilfe eines Professionellen, der dir die Schritte, denen du folgen solltest, auf eine kontrolliertere und wirksamere Art nahe bringt.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ich_bin_traurig_%E2%80%93_Die_Physiologie_der_Trauer\"><\/span><strong>Ich bin traurig &#8211; Die Physiologie der Trauer<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wenn wir Trauer empfinden, geraten die Hormonlevel unseres Organismus aus dem Gleichgewicht und sorgen f\u00fcr folgende Effekte:<\/p>\n<ul>\n<li><strong>Die Trauer zeichnet sich durch Ver\u00e4nderungen im vegetativen Nervensystem (VNS) aus:\u00a0<\/strong>das VNS erleidet einen gewissen Anstieg der Herzfrequenz und des Blutdrucks.<\/li>\n<li>In einer Studie von\u00a0<strong>Cacioppo, Klein und Hatfield<\/strong>\u00a0wurde bewiesen, dass die Trauer eine Verringerung des Interesses an anderen Aktivit\u00e4ten in uns hervorruft.<\/li>\n<li><strong>Traurigsein ersch\u00f6pft:<\/strong>\u00a0Das Gehirn steht st\u00e4ndig unter Stress und verlangt gro\u00dfe Mengen an Glukose. Wir f\u00fchlen uns schlapp und wissen nicht genau warum.<\/li>\n<li><strong>Wenn wir traurig sind, k\u00f6nnen wir den Geschmackssinn f\u00fcr S\u00fc\u00dfes verlieren:\u00a0<\/strong>Unsere Rezeptoren werden weniger. Deshalb k\u00f6nnen wir unheimlich viele S\u00fc\u00dfigkeiten essen ohne wahrzunehmen, wie viel wir gegessen haben.<\/li>\n<li><strong>Der Serotoninspiegel sinkt:\u00a0<\/strong>Diese Substanz ist daf\u00fcr verantwortlich, unsere Stimmung im Gleichgewicht zu halten.<\/li>\n<\/ul>\n<p>Zur <strong>evolutiven Funktion der Trauer<\/strong> gibt es verschiedene Meinungen. Einerseits glaubt man, dass uns die Traurigkeit dazu dient, unsere Energien nach innen lenken. Wir h\u00f6ren auf, auf unsere Umgebung zu achten, um uns auf uns selbst du konzentrieren. Andererseits dient sie als Hilferuf. Die anderen richten ihrer Aufmerksamkeit auf uns und helfen uns so, unseren emotionalen Verlust zu \u00fcberwinden.<\/p>\n<p>Quelle: Bel\u00e9n Benito, Psychologin bei CogniFit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Ich kann nicht mehr. Ich hab es satt.&#8221; &#8220;Ich bin traurig. Ich ertrage mein Leben nicht. Ich will mich nicht vom Sofa bewegen.&#8221; &#8220;Warum hat [&#8230;]<\/p>\n","protected":false},"author":40,"featured_media":10733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4220,4238],"tags":[4329,6293,4290,3909,4326,4328,4327,4330,4333,4331,4332],"class_list":["post-10782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gehirngesundheit","category-gesundheit","tag-die-trauer-ueberwinden","tag-hormonas-de","tag-hormonas","tag-hormone","tag-ich-bin-traurig","tag-nervensystem","tag-physiologie-der-trauer","tag-trauer","tag-trauer-oder-depression","tag-traurigkeit","tag-traurigkeit-oder-depression"],"_links":{"self":[{"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/posts\/10782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/comments?post=10782"}],"version-history":[{"count":0,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/posts\/10782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/media\/10733"}],"wp:attachment":[{"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/media?parent=10782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/categories?post=10782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yourbrain.health\/de\/wp-json\/wp\/v2\/tags?post=10782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}